{"id":19528,"count":1,"description":"","link":"https:\/\/www.em.com.br\/emfoco\/tag\/tribunal-de-justica-do-rio-de-janeiro\/","name":"Tribunal de Justi\u00e7a do Rio de Janeiro","slug":"tribunal-de-justica-do-rio-de-janeiro","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivo de Tribunal de Justi\u00e7a do Rio de Janeiro - Estado de Minas - Em foco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.em.com.br\/emfoco\/tag\/tribunal-de-justica-do-rio-de-janeiro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de Tribunal de Justi\u00e7a do Rio de Janeiro - Estado de Minas - Em foco\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.em.com.br\/emfoco\/tag\/tribunal-de-justica-do-rio-de-janeiro\/\" \/>\n<meta property=\"og:site_name\" content=\"Estado de Minas - Em foco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de Tribunal de Justi\u00e7a do Rio de Janeiro - Estado de Minas - Em foco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.em.com.br\/emfoco\/tag\/tribunal-de-justica-do-rio-de-janeiro\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivo de Tribunal de Justi\u00e7a do Rio de Janeiro - Estado de Minas - Em foco","og_url":"https:\/\/www.em.com.br\/emfoco\/tag\/tribunal-de-justica-do-rio-de-janeiro\/","og_site_name":"Estado de Minas - Em foco","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.em.com.br\/emfoco\/tag\/tribunal-de-justica-do-rio-de-janeiro\/","url":"https:\/\/www.em.com.br\/emfoco\/tag\/tribunal-de-justica-do-rio-de-janeiro\/","name":"Arquivo de Tribunal de Justi\u00e7a do Rio de Janeiro - Estado de Minas - Em foco","isPartOf":{"@id":"https:\/\/www.em.com.br\/emfoco\/#website"},"breadcrumb":{"@id":"https:\/\/www.em.com.br\/emfoco\/tag\/tribunal-de-justica-do-rio-de-janeiro\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.em.com.br\/emfoco\/tag\/tribunal-de-justica-do-rio-de-janeiro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.em.com.br\/emfoco\/"},{"@type":"ListItem","position":2,"name":"Tribunal de Justi\u00e7a do Rio de Janeiro"}]},{"@type":"WebSite","@id":"https:\/\/www.em.com.br\/emfoco\/#website","url":"https:\/\/www.em.com.br\/emfoco\/","name":"Estado de Minas - Em foco","description":"Acompanhe as \u00faltimas not\u00edcias e fique bem informado sobre tudo o que acontece em Minas Gerais, Brasil e no mundo.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.em.com.br\/emfoco\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/tags\/19528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/posts?tags=19528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}