{"id":73435,"date":"2025-07-12T19:08:00","date_gmt":"2025-07-12T22:08:00","guid":{"rendered":"https:\/\/www.em.com.br\/emfoco\/?p=73435"},"modified":"2025-07-11T19:40:17","modified_gmt":"2025-07-11T22:40:17","slug":"a-ligacao-inesperada-da-origem-do-wi-fi-com-radares-da-segunda-guerra-mundial","status":"publish","type":"post","link":"https:\/\/www.em.com.br\/emfoco\/2025\/07\/12\/a-ligacao-inesperada-da-origem-do-wi-fi-com-radares-da-segunda-guerra-mundial\/","title":{"rendered":"A liga\u00e7\u00e3o inesperada da origem do Wi-Fi com radares da Segunda Guerra Mundial"},"content":{"rendered":"\n<p>A revolu\u00e7\u00e3o tecnol\u00f3gica que o <strong>Wi-Fi <\/strong>trouxe para o cotidiano est\u00e1 longe de ser apenas um progresso recente e isolado. Suas origens remontam a eventos e inven\u00e7\u00f5es de eras passadas, mais especificamente, \u00e0 \u00e9poca da <strong><a href=\"https:\/\/brasilescola.uol.com.br\/historiag\/segunda-guerra-mundial.htm\" target=\"_blank\" rel=\"noreferrer noopener\">Segunda Guerra Mundial<\/a><\/strong>. Embora esse fato possa surpreender muitos, a base tecnol\u00f3gica do Wi-Fi est\u00e1 intimamente ligada aos desenvolvimentos tecnol\u00f3gicos daquele per\u00edodo conturbado.<\/p>\n\n\n\n<p><strong>A d\u00e9cada de 1940 foi marcada por intensos avan\u00e7os tecnol\u00f3gicos, com o radar surgindo como uma ferramenta cr\u00edtica. <\/strong>Estes equipamentos n\u00e3o s\u00f3 ajudaram a mudar o curso da guerra, mas tamb\u00e9m plantaram sementes que gerariam tecnologias que hoje fazem parte da vida di\u00e1ria. A conex\u00e3o entre o Wi-Fi e o radar \u00e9 uma hist\u00f3ria intrincada de inova\u00e7\u00e3o e reapropria\u00e7\u00e3o tecnol\u00f3gica.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como o radar da Segunda Guerra Mundial influenciou a cria\u00e7\u00e3o do Wi-Fi?<\/h2>\n\n\n\n<p>Durante a Segunda Guerra Mundial, cientistas e engenheiros de v\u00e1rias na\u00e7\u00f5es foram for\u00e7ados a inovar rapidamente. <strong>A busca pelo dom\u00ednio no campo de batalha impulsionou avan\u00e7os na tecnologia de radar, que eram usados para detectar aeronaves inimigas \u00e0 dist\u00e2ncia.<\/strong> Ap\u00f3s a guerra, os componentes e conceitos desenvolvidos para os radares come\u00e7aram a ser analisados para outras utilidades.<\/p>\n\n\n\n<p>Uma das tecnologias-chave que emergiu disso foi o uso de ondas de r\u00e1dio para a detec\u00e7\u00e3o e comunica\u00e7\u00e3o. Inicialmente, os sinais utilizados nos radares n\u00e3o eram destinados para comunica\u00e7\u00e3o civil, mas a vis\u00e3o de alguns cientistas iluminou o potencial que essas ondas tinham para conectar dispositivos no cotidiano civil. Assim, a ponte entre o radar e tecnologias modernas como o Wi-Fi come\u00e7ou a se formar. Inclusive, alguns feitos espec\u00edficos nesse per\u00edodo, como o desenvolvimento do magnetron, contribu\u00edram diretamente para a efici\u00eancia das transmiss\u00f5es de sinais de r\u00e1dio, posteriormente utilizadas em comunica\u00e7\u00f5es sem fio.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/06\/internet_1749645218162-1024x576.jpg\" alt=\"Da Guerra Fria ao Wi-Fi! Conhe\u00e7a a surpreendente hist\u00f3ria por tr\u00e1s da origem da internet\" class=\"wp-image-58746\" srcset=\"https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/06\/internet_1749645218162-1024x576.jpg 1024w, https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/06\/internet_1749645218162-300x169.jpg 300w, https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/06\/internet_1749645218162-768x432.jpg 768w, https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/06\/internet_1749645218162-750x422.jpg 750w, https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/06\/internet_1749645218162-1140x641.jpg 1140w, https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/06\/internet_1749645218162.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Representa\u00e7\u00e3o de internet global &#8211; Cr\u00e9ditos: depositphotos.com \/ stori<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Qual foi o papel do espectro de r\u00e1dio na origem do Wi-Fi?<\/h2>\n\n\n\n<p><strong>O espectro de r\u00e1dio desempenhou um papel crucial na transi\u00e7\u00e3o das tecnologias de radar para o desenvolvimento do Wi-Fi.<\/strong> Este espectro, que abrange uma gama de frequ\u00eancias das quais o radar tamb\u00e9m fazia uso, acabou sendo uma das heran\u00e7as mais valiosas da Segunda Guerra Mundial. Governos e cientistas perceberam que parte desse espectro podia ser liberada para fins civis, abrindo caminho para novas tecnologias.<\/p>\n\n\n\n<p>Nos anos que se seguiram, essa libera\u00e7\u00e3o do espectro permitiu o desenvolvimento de m\u00faltiplas tecnologias de comunica\u00e7\u00e3o sem fio, culminando na cria\u00e7\u00e3o do Wi-Fi. <strong>Sem o espectro de r\u00e1dio ocupado pelos radares durante a guerra, as frequ\u00eancias que agora abrigam o Wi-Fi talvez nunca tivessem sido exploradas para essa finalidade.<\/strong> Essa foi uma aplica\u00e7\u00e3o pac\u00edfica e transformadora de uma tecnologia inicialmente criada para fins militares.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como os desenvolvimentos militares contribu\u00edram para as comunica\u00e7\u00f5es modernas?<\/h2>\n\n\n\n<p>Al\u00e9m do impacto direto das frequ\u00eancias de r\u00e1dio, a tecnologia militar usada para melhorar a precis\u00e3o e a resolu\u00e7\u00e3o dos radares tamb\u00e9m contribuiu enormemente para as comunica\u00e7\u00f5es modernas. <strong>Este aperfei\u00e7oamento de <a href=\"https:\/\/www.em.com.br\/emfoco\/2025\/07\/07\/com-o-avanco-da-tecnologia-inteligencias-artificiais-ja-estao-sendo-capaz-de-fazer-leitura-labial\/\" target=\"_blank\" rel=\"noreferrer noopener\">tecnologia <\/a>antiga se transformou em um catalisador para o desenvolvimento de sistemas de comunica\u00e7\u00e3o mais eficientes e r\u00e1pidos, caracter\u00edsticas essenciais no Wi-Fi de hoje.<\/strong><\/p>\n\n\n\n<p>Estas inova\u00e7\u00f5es militares n\u00e3o permaneceram limitadas \u00e0s for\u00e7as armadas. Ap\u00f3s a guerra, cientistas transferiram muitas dessas ideias e tecnologias para o setor civil. Entre elas, pode-se citar o uso de t\u00e9cnicas como o salto de frequ\u00eancia, desenvolvido inicialmente para dificultar a intercepta\u00e7\u00e3o de sinais militares, e que mais tarde ajudaria a evitar interfer\u00eancias nas redes Wi-Fi civis. As melhorias que tinham como objetivo originalmente a efic\u00e1cia militar foram adaptadas para otimizar redes sem fio, resultando na cria\u00e7\u00e3o de servi\u00e7os que moldaram o modo como nos conectamos atualmente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O Wi-Fi seria poss\u00edvel sem os avan\u00e7os do passado?<\/h2>\n\n\n\n<p><strong>A intr\u00ednseca liga\u00e7\u00e3o entre avan\u00e7os tecnol\u00f3gicos militares e desenvolvimentos civis continua a ser um tema de discuss\u00e3o entre historiadores e engenheiros.<\/strong> Considerando as circunst\u00e2ncias e a demanda urgente durante a Segunda Guerra Mundial, muitos acreditam que o ritmo dos desenvolvimentos tecnol\u00f3gicos teria sido significativamente mais lento sem tal influ\u00eancia.<\/p>\n\n\n\n<p>\u00c9 interessante ponderar sobre como a busca por solu\u00e7\u00f5es em tempos de crise frequentemente leva a inova\u00e7\u00f5es que perduram e se adaptam para melhorar a vida cotidiana. O Wi-Fi, agora uma pe\u00e7a vital de nossa infraestrutura tecnol\u00f3gica, deve sua realidade em parte \u00e0quela \u00e9poca de intempestiva inova\u00e7\u00e3o, provando que as tecnologias militares podem ser uma poderosa for\u00e7a impulsionadora tamb\u00e9m para benef\u00edcios civis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A revolu\u00e7\u00e3o tecnol\u00f3gica que o Wi-Fi trouxe para o cotidiano est\u00e1 longe de ser apenas um progresso recente e isolado. Suas origens remontam a eventos e inven\u00e7\u00f5es de eras passadas, mais especificamente, \u00e0 \u00e9poca da Segunda Guerra Mundial. Embora esse fato possa surpreender muitos, a base tecnol\u00f3gica do Wi-Fi est\u00e1 intimamente ligada aos desenvolvimentos tecnol\u00f3gicos [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":58744,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"footnotes":""},"categories":[8819,1],"tags":[3686,181,161,3799],"class_list":["post-73435","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades","category-noticias","tag-radar","tag-segunda-guerra-mundial","tag-tecnologia","tag-wi-fi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A liga\u00e7\u00e3o inesperada da origem do Wi-Fi com radares da Segunda Guerra Mundial - Estado de Minas - Em foco<\/title>\n<meta name=\"description\" content=\"O Wi-Fi moderno tem ra\u00edzes nos radares da Segunda Guerra Mundial. Saiba como a tecnologia militar impulsionou a nossa conex\u00e3o di\u00e1ria.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.em.com.br\/emfoco\/2025\/07\/12\/a-ligacao-inesperada-da-origem-do-wi-fi-com-radares-da-segunda-guerra-mundial\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A liga\u00e7\u00e3o inesperada da origem do Wi-Fi com radares da Segunda Guerra Mundial - Estado de Minas - Em foco\" \/>\n<meta property=\"og:description\" content=\"O Wi-Fi moderno tem ra\u00edzes nos radares da Segunda Guerra Mundial. Saiba como a tecnologia militar impulsionou a nossa conex\u00e3o di\u00e1ria.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.em.com.br\/emfoco\/2025\/07\/12\/a-ligacao-inesperada-da-origem-do-wi-fi-com-radares-da-segunda-guerra-mundial\/\" \/>\n<meta property=\"og:site_name\" content=\"Estado de Minas - Em foco\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-12T22:08:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-11T22:40:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/06\/internet_1749645195025.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1279\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriel Martins\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Martins\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A liga\u00e7\u00e3o inesperada da origem do Wi-Fi com radares da Segunda Guerra Mundial - Estado de Minas - Em foco","description":"O Wi-Fi moderno tem ra\u00edzes nos radares da Segunda Guerra Mundial. Saiba como a tecnologia militar impulsionou a nossa conex\u00e3o di\u00e1ria.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.em.com.br\/emfoco\/2025\/07\/12\/a-ligacao-inesperada-da-origem-do-wi-fi-com-radares-da-segunda-guerra-mundial\/","og_locale":"pt_BR","og_type":"article","og_title":"A liga\u00e7\u00e3o inesperada da origem do Wi-Fi com radares da Segunda Guerra Mundial - Estado de Minas - Em foco","og_description":"O Wi-Fi moderno tem ra\u00edzes nos radares da Segunda Guerra Mundial. Saiba como a tecnologia militar impulsionou a nossa conex\u00e3o di\u00e1ria.","og_url":"https:\/\/www.em.com.br\/emfoco\/2025\/07\/12\/a-ligacao-inesperada-da-origem-do-wi-fi-com-radares-da-segunda-guerra-mundial\/","og_site_name":"Estado de Minas - Em foco","article_published_time":"2025-07-12T22:08:00+00:00","article_modified_time":"2025-07-11T22:40:17+00:00","og_image":[{"width":1279,"height":720,"url":"https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/06\/internet_1749645195025.jpg","type":"image\/jpeg"}],"author":"Gabriel Martins","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gabriel Martins","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.em.com.br\/emfoco\/2025\/07\/12\/a-ligacao-inesperada-da-origem-do-wi-fi-com-radares-da-segunda-guerra-mundial\/","url":"https:\/\/www.em.com.br\/emfoco\/2025\/07\/12\/a-ligacao-inesperada-da-origem-do-wi-fi-com-radares-da-segunda-guerra-mundial\/","name":"A liga\u00e7\u00e3o inesperada da origem do Wi-Fi com radares da Segunda Guerra Mundial - Estado de Minas - Em foco","isPartOf":{"@id":"https:\/\/www.em.com.br\/emfoco\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.em.com.br\/emfoco\/2025\/07\/12\/a-ligacao-inesperada-da-origem-do-wi-fi-com-radares-da-segunda-guerra-mundial\/#primaryimage"},"image":{"@id":"https:\/\/www.em.com.br\/emfoco\/2025\/07\/12\/a-ligacao-inesperada-da-origem-do-wi-fi-com-radares-da-segunda-guerra-mundial\/#primaryimage"},"thumbnailUrl":"https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/06\/internet_1749645195025.jpg","datePublished":"2025-07-12T22:08:00+00:00","dateModified":"2025-07-11T22:40:17+00:00","author":{"@id":"https:\/\/www.em.com.br\/emfoco\/#\/schema\/person\/1c9ddeab18b98abeffef834667bcf08a"},"description":"O Wi-Fi moderno tem ra\u00edzes nos radares da Segunda Guerra Mundial. Saiba como a tecnologia militar impulsionou a nossa conex\u00e3o di\u00e1ria.","breadcrumb":{"@id":"https:\/\/www.em.com.br\/emfoco\/2025\/07\/12\/a-ligacao-inesperada-da-origem-do-wi-fi-com-radares-da-segunda-guerra-mundial\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.em.com.br\/emfoco\/2025\/07\/12\/a-ligacao-inesperada-da-origem-do-wi-fi-com-radares-da-segunda-guerra-mundial\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.em.com.br\/emfoco\/2025\/07\/12\/a-ligacao-inesperada-da-origem-do-wi-fi-com-radares-da-segunda-guerra-mundial\/#primaryimage","url":"https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/06\/internet_1749645195025.jpg","contentUrl":"https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/06\/internet_1749645195025.jpg","width":1279,"height":720,"caption":"Internet - Cr\u00e9ditos: depositphotos.com \/ cookiecutter"},{"@type":"BreadcrumbList","@id":"https:\/\/www.em.com.br\/emfoco\/2025\/07\/12\/a-ligacao-inesperada-da-origem-do-wi-fi-com-radares-da-segunda-guerra-mundial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.em.com.br\/emfoco\/"},{"@type":"ListItem","position":2,"name":"A liga\u00e7\u00e3o inesperada da origem do Wi-Fi com radares da Segunda Guerra Mundial"}]},{"@type":"WebSite","@id":"https:\/\/www.em.com.br\/emfoco\/#website","url":"https:\/\/www.em.com.br\/emfoco\/","name":"Estado de Minas - Em foco","description":"Acompanhe as \u00faltimas not\u00edcias e fique bem informado sobre tudo o que acontece em Minas Gerais, Brasil e no mundo.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.em.com.br\/emfoco\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.em.com.br\/emfoco\/#\/schema\/person\/1c9ddeab18b98abeffef834667bcf08a","name":"Gabriel Martins","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.em.com.br\/emfoco\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f0f1e2efdfd88f1ad2cb08c5c2731e50?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f0f1e2efdfd88f1ad2cb08c5c2731e50?s=96&d=mm&r=g","caption":"Gabriel Martins"},"sameAs":["https:\/\/www.em.com.br\/emfoco\/"],"url":"https:\/\/www.em.com.br\/emfoco\/author\/gabrielmartinsmyth\/"}]}},"_links":{"self":[{"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/posts\/73435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/comments?post=73435"}],"version-history":[{"count":2,"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/posts\/73435\/revisions"}],"predecessor-version":[{"id":73459,"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/posts\/73435\/revisions\/73459"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/media\/58744"}],"wp:attachment":[{"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/media?parent=73435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/categories?post=73435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/tags?post=73435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}