{"id":34497,"date":"2025-04-03T19:40:00","date_gmt":"2025-04-03T22:40:00","guid":{"rendered":"https:\/\/www.em.com.br\/emfoco\/?p=34497"},"modified":"2025-04-02T15:31:33","modified_gmt":"2025-04-02T18:31:33","slug":"ufmg-sedia-a-cupula-global-da-juventude-pelo-clima-2025","status":"publish","type":"post","link":"https:\/\/www.em.com.br\/emfoco\/2025\/04\/03\/ufmg-sedia-a-cupula-global-da-juventude-pelo-clima-2025\/","title":{"rendered":"UFMG sedia a C\u00fapula Global da Juventude pelo Clima 2025"},"content":{"rendered":"\n<p>De 2 a 5 de abril, a <strong><a href=\"https:\/\/ufmg.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Universidade Federal de Minas Gerais (UFMG)<\/a><\/strong> se torna o epicentro das discuss\u00f5es sobre o futuro clim\u00e1tico do planeta ao sediar a <strong>C\u00fapula Global da Juventude pelo Clima 2025<\/strong>. O evento re\u00fane 200 jovens l\u00edderes clim\u00e1ticos de mais de 40 pa\u00edses em <strong>Belo Horizonte<\/strong>, al\u00e9m de outros 300 participantes que acompanham virtualmente. Organizada pelo <strong>Global Youth Leadership Center (GYLC)<\/strong> em parceria com a UFMG, a c\u00fapula busca capacitar a juventude para liderar a\u00e7\u00f5es contra a crise clim\u00e1tica, refor\u00e7ando o papel da ci\u00eancia e da biodiversidade na constru\u00e7\u00e3o de solu\u00e7\u00f5es sustent\u00e1veis.<\/p>\n\n\n\n<p>A preocupa\u00e7\u00e3o com o meio ambiente j\u00e1 n\u00e3o \u00e9 uma quest\u00e3o apenas para o futuro. Os impactos das <strong><a href=\"https:\/\/www.em.com.br\/emfoco\/2025\/01\/23\/inteligencia-artificial-e-mudancas-climaticas-uma-nova-ferramenta-de-previsao\/\" target=\"_blank\" rel=\"noreferrer noopener\">mudan\u00e7as clim\u00e1ticas<\/a><\/strong> s\u00e3o sentidos em todo o mundo, e a juventude do Sul Global, incluindo o Brasil, enfrenta desafios ainda maiores devido \u00e0 vulnerabilidade socioecon\u00f4mica e ambiental dessas regi\u00f5es. Durante o evento, debates, oficinas e apresenta\u00e7\u00f5es de projetos visam fortalecer o engajamento dos jovens na busca por pol\u00edticas mais eficazes na luta contra o aquecimento global.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O papel estrat\u00e9gico da UFMG e o apoio de institui\u00e7\u00f5es brasileiras<\/h2>\n\n\n\n<p>A escolha da UFMG para sediar a c\u00fapula reflete sua lideran\u00e7a acad\u00eamica na defesa da ci\u00eancia e da sustentabilidade. A reitora <strong>Sandra Regina Goulart Almeida<\/strong> destaca a import\u00e2ncia de empoderar a juventude nesse cen\u00e1rio de incertezas clim\u00e1ticas. \u201c<em>J\u00e1 estamos sentindo os efeitos das mudan\u00e7as clim\u00e1ticas, e capacitar os jovens para atuarem nessa causa \u00e9 essencial<\/em>\u201d, afirma.<\/p>\n\n\n\n<p>A realiza\u00e7\u00e3o do evento conta com o apoio de grandes institui\u00e7\u00f5es brasileiras, como a <strong>Cemig<\/strong> (patrocinadora ouro), a <strong>Fiemg<\/strong> (patrocinadora prata) e a <strong>Itaminas <\/strong>(parceira de descarboniza\u00e7\u00e3o). O <strong>Instituto de Ci\u00eancias Biol\u00f3gicas (ICB) <\/strong>da UFMG \u00e9 a unidade acad\u00eamica respons\u00e1vel por coordenar as atividades e receber os participantes.<\/p>\n\n\n\n<p>O professor <strong>Ricardo Gon\u00e7alves<\/strong>, diretor do ICB, refor\u00e7a o impacto global da c\u00fapula. \u201c<em>Esse pode ser o evento preparat\u00f3rio mais importante para a COP30. Tivemos mais de quatro mil candidaturas, e os 200 selecionados representam uma elite de jovens engajados na busca por solu\u00e7\u00f5es clim\u00e1ticas<\/em>\u201d, explica.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/04\/clima-global_1743619768432-1024x576.jpg\" alt=\"\" class=\"wp-image-34574\" srcset=\"https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/04\/clima-global_1743619768432-1024x576.jpg 1024w, https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/04\/clima-global_1743619768432-300x169.jpg 300w, https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/04\/clima-global_1743619768432-768x432.jpg 768w, https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/04\/clima-global_1743619768432-750x422.jpg 750w, https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/04\/clima-global_1743619768432-1140x641.jpg 1140w, https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/04\/clima-global_1743619768432.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Clima global &#8211; Cr\u00e9ditos: depositphotos.com \/ ajafoto<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Pr\u00eamios para projetos ambientais e a Carta de Belo Horizonte<\/h2>\n\n\n\n<p>Um dos destaques da c\u00fapula \u00e9 a premia\u00e7\u00e3o de dez lideran\u00e7as juvenis de regi\u00f5es vulner\u00e1veis, que receber\u00e3o US$ 1.000 cada para implementar projetos ambientais em suas comunidades. Os vencedores ser\u00e3o escolhidos com base em criatividade, viabilidade e impacto potencial das propostas.<\/p>\n\n\n\n<p>Al\u00e9m disso, a c\u00fapula resultar\u00e1 na elabora\u00e7\u00e3o da \u201c<strong>Carta de Belo Horizonte<\/strong>\u201d, um documento oficial com diretrizes e recomenda\u00e7\u00f5es sobre a crise clim\u00e1tica e a preserva\u00e7\u00e3o ambiental. Essa carta ser\u00e1 enviada a autoridades globais e servir\u00e1 como um dos pilares das discuss\u00f5es na<strong> COP30<\/strong>, que acontece em novembro, em <strong>Bel\u00e9m (PA)<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">A import\u00e2ncia da biodiversidade no combate \u00e0 crise clim\u00e1tica<\/h2>\n\n\n\n<p>A biodiversidade ser\u00e1 um dos temas centrais da c\u00fapula, gra\u00e7as ao trabalho do professor <strong>Geraldo Wilson Fernandes<\/strong>, especialista em ecologia e coordenador do <strong>Programa de Pesquisa em Biodiversidade do Minist\u00e9rio da Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o (MCTI)<\/strong>. Ele defende que qualquer estrat\u00e9gia de combate \u00e0s mudan\u00e7as clim\u00e1ticas deve estar diretamente ligada \u00e0 preserva\u00e7\u00e3o da biodiversidade.<\/p>\n\n\n\n<p>\u201c<em>N\u00e3o adianta falar em crise clim\u00e1tica sem considerar a biodiversidade. A vida no planeta depende dela, e, uma vez perdida, n\u00e3o h\u00e1 como recuperar. Precisamos incluir essa discuss\u00e3o nas estrat\u00e9gias ambientais para garantir um futuro mais sustent\u00e1vel<\/em>\u201d, enfatiza Fernandes.<\/p>\n\n\n\n<p>A inclus\u00e3o da biodiversidade nas discuss\u00f5es foi prontamente aceita pelos organizadores do evento, refor\u00e7ando a necessidade de integrar diferentes abordagens na luta contra o colapso ambiental.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/04\/clima-global_1743619720901-1024x576.jpg\" alt=\"\" class=\"wp-image-34573\" srcset=\"https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/04\/clima-global_1743619720901-1024x576.jpg 1024w, https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/04\/clima-global_1743619720901-300x169.jpg 300w, https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/04\/clima-global_1743619720901-768x432.jpg 768w, https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/04\/clima-global_1743619720901-750x422.jpg 750w, https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/04\/clima-global_1743619720901-1140x641.jpg 1140w, https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/04\/clima-global_1743619720901.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Clima global &#8211; Cr\u00e9ditos: depositphotos.com \/ varuna<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Povos ind\u00edgenas e justi\u00e7a clim\u00e1tica no centro das discuss\u00f5es<\/h2>\n\n\n\n<p>A jovem ativista ind\u00edgena <strong>Rayane Xipaia<\/strong>, do <strong>Par\u00e1<\/strong>, ser\u00e1 uma das principais vozes na c\u00fapula, trazendo a perspectiva dos povos origin\u00e1rios sobre a preserva\u00e7\u00e3o ambiental. Ela defende que os ind\u00edgenas t\u00eam muito a ensinar sobre conviv\u00eancia sustent\u00e1vel com a floresta e que sua ci\u00eancia e tecnologia s\u00e3o fundamentais para combater as mudan\u00e7as clim\u00e1ticas.<\/p>\n\n\n\n<p>\u201c<em>Os povos ind\u00edgenas sempre coexistiram com a floresta sem destru\u00ed-la. Temos muito conhecimento a compartilhar, e essa sabedoria precisa ser valorizada\u201d, <\/em>afirma Rayane.<\/p>\n\n\n\n<p>A ativista tamb\u00e9m abordar\u00e1 a desigualdade social e seus impactos na crise clim\u00e1tica. \u201c<em>Quem mais sofre com essa crise s\u00e3o as popula\u00e7\u00f5es mais vulner\u00e1veis. H\u00e1 uma enorme diferen\u00e7a entre perder a casa em uma enchente e assistir \u00e0 enchente de uma cobertura de luxo. Precisamos de pol\u00edticas p\u00fablicas que reduzam essas desigualdades<\/em>\u201d, pontua.<\/p>\n\n\n\n<p>Al\u00e9m da participa\u00e7\u00e3o de Rayane, jovens l\u00edderes clim\u00e1ticos de pa\u00edses como <strong>Jap\u00e3o, Qu\u00eania, \u00c1frica do Sul, Bangladesh, Peru e Gana<\/strong> ter\u00e3o a oportunidade de apresentar propostas diretamente \u00e0s autoridades presentes. O CEO da GYLC, <strong>Ejaj Ahmad<\/strong>, refor\u00e7a a import\u00e2ncia do evento: \u201c<em>Essa c\u00fapula \u00e9 uma oportunidade crucial para que os jovens influenciem as decis\u00f5es globais sobre o clima antes da COP30<\/em>\u201d.<\/p>\n\n\n\n<p>Com a UFMG como palco desse encontro global, a juventude se prepara para liderar a transforma\u00e7\u00e3o clim\u00e1tica que o mundo tanto precisa.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De 2 a 5 de abril, a Universidade Federal de Minas Gerais (UFMG) se torna o epicentro das discuss\u00f5es sobre o futuro clim\u00e1tico do planeta ao sediar a C\u00fapula Global da Juventude pelo Clima 2025. O evento re\u00fane 200 jovens l\u00edderes clim\u00e1ticos de mais de 40 pa\u00edses em Belo Horizonte, al\u00e9m de outros 300 participantes [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":34572,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"footnotes":""},"categories":[138,1],"tags":[152,5667,2165],"class_list":["post-34497","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo","category-noticias","tag-clima","tag-globalizacao","tag-mudancas-climaticas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>UFMG sedia a C\u00fapula Global da Juventude pelo Clima 2025 - Estado de Minas - Em foco<\/title>\n<meta name=\"description\" content=\"A C\u00fapula Global da Juventude pelo Clima 2025 acontece em BH e destaca o papel da biodiversidade na luta contra o aquecimento global.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.em.com.br\/emfoco\/2025\/04\/03\/ufmg-sedia-a-cupula-global-da-juventude-pelo-clima-2025\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UFMG sedia a C\u00fapula Global da Juventude pelo Clima 2025 - Estado de Minas - Em foco\" \/>\n<meta property=\"og:description\" content=\"A C\u00fapula Global da Juventude pelo Clima 2025 acontece em BH e destaca o papel da biodiversidade na luta contra o aquecimento global.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.em.com.br\/emfoco\/2025\/04\/03\/ufmg-sedia-a-cupula-global-da-juventude-pelo-clima-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Estado de Minas - Em foco\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-03T22:40:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-02T18:31:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/04\/clima-global_1743619683348.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andre\u0301 Rangel\u00a0\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andre\u0301 Rangel\u00a0\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UFMG sedia a C\u00fapula Global da Juventude pelo Clima 2025 - Estado de Minas - Em foco","description":"A C\u00fapula Global da Juventude pelo Clima 2025 acontece em BH e destaca o papel da biodiversidade na luta contra o aquecimento global.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.em.com.br\/emfoco\/2025\/04\/03\/ufmg-sedia-a-cupula-global-da-juventude-pelo-clima-2025\/","og_locale":"pt_BR","og_type":"article","og_title":"UFMG sedia a C\u00fapula Global da Juventude pelo Clima 2025 - Estado de Minas - Em foco","og_description":"A C\u00fapula Global da Juventude pelo Clima 2025 acontece em BH e destaca o papel da biodiversidade na luta contra o aquecimento global.","og_url":"https:\/\/www.em.com.br\/emfoco\/2025\/04\/03\/ufmg-sedia-a-cupula-global-da-juventude-pelo-clima-2025\/","og_site_name":"Estado de Minas - Em foco","article_published_time":"2025-04-03T22:40:00+00:00","article_modified_time":"2025-04-02T18:31:33+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/04\/clima-global_1743619683348.jpg","type":"image\/jpeg"}],"author":"Andre\u0301 Rangel\u00a0","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Andre\u0301 Rangel\u00a0","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.em.com.br\/emfoco\/2025\/04\/03\/ufmg-sedia-a-cupula-global-da-juventude-pelo-clima-2025\/","url":"https:\/\/www.em.com.br\/emfoco\/2025\/04\/03\/ufmg-sedia-a-cupula-global-da-juventude-pelo-clima-2025\/","name":"UFMG sedia a C\u00fapula Global da Juventude pelo Clima 2025 - Estado de Minas - Em foco","isPartOf":{"@id":"https:\/\/www.em.com.br\/emfoco\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.em.com.br\/emfoco\/2025\/04\/03\/ufmg-sedia-a-cupula-global-da-juventude-pelo-clima-2025\/#primaryimage"},"image":{"@id":"https:\/\/www.em.com.br\/emfoco\/2025\/04\/03\/ufmg-sedia-a-cupula-global-da-juventude-pelo-clima-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/04\/clima-global_1743619683348.jpg","datePublished":"2025-04-03T22:40:00+00:00","dateModified":"2025-04-02T18:31:33+00:00","author":{"@id":"https:\/\/www.em.com.br\/emfoco\/#\/schema\/person\/60eda09c1fedf0d6891f4cef4b60b8b8"},"description":"A C\u00fapula Global da Juventude pelo Clima 2025 acontece em BH e destaca o papel da biodiversidade na luta contra o aquecimento global.","breadcrumb":{"@id":"https:\/\/www.em.com.br\/emfoco\/2025\/04\/03\/ufmg-sedia-a-cupula-global-da-juventude-pelo-clima-2025\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.em.com.br\/emfoco\/2025\/04\/03\/ufmg-sedia-a-cupula-global-da-juventude-pelo-clima-2025\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.em.com.br\/emfoco\/2025\/04\/03\/ufmg-sedia-a-cupula-global-da-juventude-pelo-clima-2025\/#primaryimage","url":"https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/04\/clima-global_1743619683348.jpg","contentUrl":"https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/04\/clima-global_1743619683348.jpg","width":1280,"height":720,"caption":"Clima global - Cr\u00e9ditos: depositphotos.com \/ kwest"},{"@type":"BreadcrumbList","@id":"https:\/\/www.em.com.br\/emfoco\/2025\/04\/03\/ufmg-sedia-a-cupula-global-da-juventude-pelo-clima-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.em.com.br\/emfoco\/"},{"@type":"ListItem","position":2,"name":"UFMG sedia a C\u00fapula Global da Juventude pelo Clima 2025"}]},{"@type":"WebSite","@id":"https:\/\/www.em.com.br\/emfoco\/#website","url":"https:\/\/www.em.com.br\/emfoco\/","name":"Estado de Minas - Em foco","description":"Acompanhe as \u00faltimas not\u00edcias e fique bem informado sobre tudo o que acontece em Minas Gerais, Brasil e no mundo.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.em.com.br\/emfoco\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.em.com.br\/emfoco\/#\/schema\/person\/60eda09c1fedf0d6891f4cef4b60b8b8","name":"Andre\u0301 Rangel\u00a0","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.em.com.br\/emfoco\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/6234dc814c77c8ef6d8bba622c787efc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6234dc814c77c8ef6d8bba622c787efc?s=96&d=mm&r=g","caption":"Andre\u0301 Rangel\u00a0"},"url":"https:\/\/www.em.com.br\/emfoco\/author\/luizmyth\/"}]}},"_links":{"self":[{"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/posts\/34497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/comments?post=34497"}],"version-history":[{"count":4,"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/posts\/34497\/revisions"}],"predecessor-version":[{"id":34575,"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/posts\/34497\/revisions\/34575"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/media\/34572"}],"wp:attachment":[{"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/media?parent=34497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/categories?post=34497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/tags?post=34497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}