{"id":19155,"date":"2025-02-13T20:20:51","date_gmt":"2025-02-13T23:20:51","guid":{"rendered":"https:\/\/www.em.com.br\/emfoco\/?p=19155"},"modified":"2025-02-12T18:37:47","modified_gmt":"2025-02-12T21:37:47","slug":"inss-2025-valores-tabela-e-como-pagar-guia-definitivo","status":"publish","type":"post","link":"https:\/\/www.em.com.br\/emfoco\/2025\/02\/13\/inss-2025-valores-tabela-e-como-pagar-guia-definitivo\/","title":{"rendered":"INSS 2025: Guia completo de valores, tabela e pagamento da guia"},"content":{"rendered":"\n<p>A partir de 2025, aut\u00f4nomos e <strong>microempreendedores individuais <\/strong>(<strong><a href=\"https:\/\/www.em.com.br\/emfoco\/2025\/01\/30\/golpes-comuns-contra-meis-entenda-e-proteja-se\/\" target=\"_blank\" rel=\"noreferrer noopener\">MEIs<\/a><\/strong>) ter\u00e3o novos valores de contribui\u00e7\u00e3o ao <strong>Instituto Nacional do Seguro Social<\/strong> (<a href=\"https:\/\/www.gov.br\/inss\/pt-br\" target=\"_blank\" rel=\"noreferrer noopener\">INSS<\/a>). O reajuste \u00e9 baseado no novo sal\u00e1rio m\u00ednimo, que foi estabelecido em R$ 1.518. A contribui\u00e7\u00e3o \u00e9 obrigat\u00f3ria para garantir acesso a benef\u00edcios previdenci\u00e1rios como aposentadoria, aux\u00edlio-doen\u00e7a e sal\u00e1rio-maternidade.<\/p>\n\n\n\n<p>O novo sal\u00e1rio m\u00ednimo entrou em vigor em 1\u00ba de janeiro de 2025, mas o primeiro boleto com o valor reajustado vence em fevereiro, pois o recolhimento sempre se refere ao m\u00eas anterior. Al\u00e9m dos aut\u00f4nomos, estudantes e desempregados com 16 anos ou mais podem contribuir de forma facultativa para manter a qualidade de segurado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como funciona a contribui\u00e7\u00e3o para aut\u00f4nomos?<\/h2>\n\n\n\n<p>Os aut\u00f4nomos podem optar por pagar a contribui\u00e7\u00e3o ao <strong>INSS <\/strong>mensalmente ou trimestralmente. O pagamento deve ser feito at\u00e9 o dia 15 do m\u00eas seguinte ao da compet\u00eancia, utilizando a <strong>Guia da Previd\u00eancia Social (GPS)<\/strong>. Se o dia 15 cair em um feriado ou fim de semana, o pagamento pode ser realizado no pr\u00f3ximo dia \u00fatil.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2024\/12\/INSS_1733068573560-1024x576.jpg\" alt=\"INSS 2025 Valores, tabela e como pagar guia Definitivo!\" class=\"wp-image-2604\" srcset=\"https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2024\/12\/INSS_1733068573560-1024x576.jpg 1024w, https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2024\/12\/INSS_1733068573560-300x169.jpg 300w, https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2024\/12\/INSS_1733068573560-768x432.jpg 768w, https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2024\/12\/INSS_1733068573560-750x422.jpg 750w, https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2024\/12\/INSS_1733068573560-1140x641.jpg 1140w, https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2024\/12\/INSS_1733068573560.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">INSS Brasilia &#8211; Cr\u00e9ditos: depositphotos.com \/ rmcarvalhobsb<\/figcaption><\/figure><\/div>\n\n\n<p>Para 2025, o calend\u00e1rio de pagamento dos aut\u00f4nomos \u00e9 o seguinte:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Janeiro: 17 de fevereiro<\/li>\n\n\n\n<li>Fevereiro: 17 de mar\u00e7o<\/li>\n\n\n\n<li>Mar\u00e7o: 15 de abril<\/li>\n\n\n\n<li>Abril: 15 de maio<\/li>\n\n\n\n<li>Maio: 16 de junho<\/li>\n\n\n\n<li>Junho: 15 de julho<\/li>\n\n\n\n<li>Julho: 15 de agosto<\/li>\n\n\n\n<li>Agosto: 15 de setembro<\/li>\n\n\n\n<li>Setembro: 15 de outubro<\/li>\n\n\n\n<li>Outubro: 17 de novembro<\/li>\n\n\n\n<li>Novembro: 15 de dezembro<\/li>\n\n\n\n<li>Dezembro: 15 de janeiro de 2026<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Quais s\u00e3o as al\u00edquotas e valores de contribui\u00e7\u00e3o?<\/h2>\n\n\n\n<p>O c\u00e1lculo da contribui\u00e7\u00e3o \u00e9 feito com base em al\u00edquotas aplicadas sobre o sal\u00e1rio de contribui\u00e7\u00e3o. As al\u00edquotas variam de acordo com o tipo de contribuinte e o benef\u00edcio desejado. Veja abaixo as op\u00e7\u00f5es dispon\u00edveis:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Contribuinte individual:<\/strong> 20% sobre o sal\u00e1rio m\u00ednimo, resultando em R$ 303,60.<\/li>\n\n\n\n<li><strong>Facultativo:<\/strong> 20% sobre o sal\u00e1rio m\u00ednimo, tamb\u00e9m totalizando R$ 303,60.<\/li>\n\n\n\n<li><strong>Contribuinte individual (sem aposentadoria por tempo de contribui\u00e7\u00e3o):<\/strong> 11% sobre o sal\u00e1rio m\u00ednimo, resultando em R$ 166,98.<\/li>\n\n\n\n<li><strong>Facultativo (sem aposentadoria por tempo de contribui\u00e7\u00e3o):<\/strong> 11% sobre o sal\u00e1rio m\u00ednimo, tamb\u00e9m totalizando R$ 166,98.<\/li>\n\n\n\n<li><strong>Facultativo de baixa renda:<\/strong> 5% sobre o sal\u00e1rio m\u00ednimo, totalizando R$ 75,90.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Como \u00e9 a contribui\u00e7\u00e3o dos MEIs?<\/h2>\n\n\n\n<p>Os microempreendedores individuais (MEIs) seguem um calend\u00e1rio de pagamento diferente e contribuem com 5% sobre o sal\u00e1rio m\u00ednimo. Al\u00e9m disso, h\u00e1 a incid\u00eancia de impostos conforme o tipo de atividade. O pagamento \u00e9 feito por meio do Documento de Arrecada\u00e7\u00e3o do Simples Nacional (DAS), que pode ser emitido no Portal do Simples Nacional ou pelo Aplicativo MEI.<\/p>\n\n\n\n<p>O calend\u00e1rio de pagamento dos MEIs para 2025 \u00e9 o seguinte:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Janeiro: 20 de fevereiro<\/li>\n\n\n\n<li>Fevereiro: 20 de mar\u00e7o<\/li>\n\n\n\n<li>Mar\u00e7o: 22 de abril<\/li>\n\n\n\n<li>Abril: 20 de maio<\/li>\n\n\n\n<li>Maio: 20 de junho<\/li>\n\n\n\n<li>Junho: 21 de julho<\/li>\n\n\n\n<li>Julho: 20 de agosto<\/li>\n\n\n\n<li>Agosto: 22 de setembro<\/li>\n\n\n\n<li>Setembro: 20 de outubro<\/li>\n\n\n\n<li>Outubro: 20 de novembro<\/li>\n\n\n\n<li>Novembro: 22 de dezembro<\/li>\n\n\n\n<li>Dezembro: 20 de janeiro de 2026<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Quais s\u00e3o os valores de contribui\u00e7\u00e3o para MEIs?<\/h2>\n\n\n\n<p>Para 2025, a contribui\u00e7\u00e3o mensal dos MEIs \u00e9 de R$ 75,90. No caso dos MEIs caminhoneiros, que devem contribuir com 12% do sal\u00e1rio m\u00ednimo, o valor \u00e9 de R$ 182,16, podendo chegar a R$ 188,16 dependendo do tipo de produto transportado e do destino.<\/p>\n\n\n\n<p>Os MEIs que realizam atividades sujeitas ao ICMS (com\u00e9rcio e ind\u00fastria) t\u00eam um acr\u00e9scimo de R$ 1 por m\u00eas no DAS. Para atividades sujeitas ao ISSQN (prestador de servi\u00e7os), o valor \u00e9 de R$ 5. Aqueles que realizam ambos os tipos de atividade precisam pagar os dois impostos, somando R$ 6 a mais na contribui\u00e7\u00e3o mensal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de 2025, aut\u00f4nomos e microempreendedores individuais (MEIs) ter\u00e3o novos valores de contribui\u00e7\u00e3o ao Instituto Nacional do Seguro Social (INSS). O reajuste \u00e9 baseado no novo sal\u00e1rio m\u00ednimo, que foi estabelecido em R$ 1.518. A contribui\u00e7\u00e3o \u00e9 obrigat\u00f3ria para garantir acesso a benef\u00edcios previdenci\u00e1rios como aposentadoria, aux\u00edlio-doen\u00e7a e sal\u00e1rio-maternidade. O novo sal\u00e1rio m\u00ednimo entrou [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":18088,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"footnotes":""},"categories":[28],"tags":[4932,174,218,4933],"class_list":["post-19155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","tag-autonomos","tag-inss","tag-mei","tag-tabela-inss-2025"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>INSS 2025: Guia completo de valores, tabela e pagamento da guia - Estado de Minas - Em foco<\/title>\n<meta name=\"description\" content=\"Descubra os novos valores da contribui\u00e7\u00e3o INSS para aut\u00f4nomos e MEIs em 2025. Garanta seus direitos e evite problemas!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.em.com.br\/emfoco\/2025\/02\/13\/inss-2025-valores-tabela-e-como-pagar-guia-definitivo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"INSS 2025: Guia completo de valores, tabela e pagamento da guia - Estado de Minas - Em foco\" \/>\n<meta property=\"og:description\" content=\"Descubra os novos valores da contribui\u00e7\u00e3o INSS para aut\u00f4nomos e MEIs em 2025. Garanta seus direitos e evite problemas!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.em.com.br\/emfoco\/2025\/02\/13\/inss-2025-valores-tabela-e-como-pagar-guia-definitivo\/\" \/>\n<meta property=\"og:site_name\" content=\"Estado de Minas - Em foco\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-13T23:20:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-12T21:37:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/02\/inss-brasil_1739068720531.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Kelvin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kelvin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"INSS 2025: Guia completo de valores, tabela e pagamento da guia - Estado de Minas - Em foco","description":"Descubra os novos valores da contribui\u00e7\u00e3o INSS para aut\u00f4nomos e MEIs em 2025. Garanta seus direitos e evite problemas!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.em.com.br\/emfoco\/2025\/02\/13\/inss-2025-valores-tabela-e-como-pagar-guia-definitivo\/","og_locale":"pt_BR","og_type":"article","og_title":"INSS 2025: Guia completo de valores, tabela e pagamento da guia - Estado de Minas - Em foco","og_description":"Descubra os novos valores da contribui\u00e7\u00e3o INSS para aut\u00f4nomos e MEIs em 2025. Garanta seus direitos e evite problemas!","og_url":"https:\/\/www.em.com.br\/emfoco\/2025\/02\/13\/inss-2025-valores-tabela-e-como-pagar-guia-definitivo\/","og_site_name":"Estado de Minas - Em foco","article_published_time":"2025-02-13T23:20:51+00:00","article_modified_time":"2025-02-12T21:37:47+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/02\/inss-brasil_1739068720531.jpg","type":"image\/jpeg"}],"author":"Kelvin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Kelvin","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.em.com.br\/emfoco\/2025\/02\/13\/inss-2025-valores-tabela-e-como-pagar-guia-definitivo\/","url":"https:\/\/www.em.com.br\/emfoco\/2025\/02\/13\/inss-2025-valores-tabela-e-como-pagar-guia-definitivo\/","name":"INSS 2025: Guia completo de valores, tabela e pagamento da guia - Estado de Minas - Em foco","isPartOf":{"@id":"https:\/\/www.em.com.br\/emfoco\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.em.com.br\/emfoco\/2025\/02\/13\/inss-2025-valores-tabela-e-como-pagar-guia-definitivo\/#primaryimage"},"image":{"@id":"https:\/\/www.em.com.br\/emfoco\/2025\/02\/13\/inss-2025-valores-tabela-e-como-pagar-guia-definitivo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/02\/inss-brasil_1739068720531.jpg","datePublished":"2025-02-13T23:20:51+00:00","dateModified":"2025-02-12T21:37:47+00:00","author":{"@id":"https:\/\/www.em.com.br\/emfoco\/#\/schema\/person\/fb0a7f48c6fbb94b83f413a80f61917d"},"description":"Descubra os novos valores da contribui\u00e7\u00e3o INSS para aut\u00f4nomos e MEIs em 2025. Garanta seus direitos e evite problemas!","breadcrumb":{"@id":"https:\/\/www.em.com.br\/emfoco\/2025\/02\/13\/inss-2025-valores-tabela-e-como-pagar-guia-definitivo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.em.com.br\/emfoco\/2025\/02\/13\/inss-2025-valores-tabela-e-como-pagar-guia-definitivo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.em.com.br\/emfoco\/2025\/02\/13\/inss-2025-valores-tabela-e-como-pagar-guia-definitivo\/#primaryimage","url":"https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/02\/inss-brasil_1739068720531.jpg","contentUrl":"https:\/\/www.em.com.br\/emfoco\/wp-content\/uploads\/2025\/02\/inss-brasil_1739068720531.jpg","width":1280,"height":720,"caption":"INSS - Cr\u00e9ditos: depositphotos.com \/ rafapress"},{"@type":"BreadcrumbList","@id":"https:\/\/www.em.com.br\/emfoco\/2025\/02\/13\/inss-2025-valores-tabela-e-como-pagar-guia-definitivo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.em.com.br\/emfoco\/"},{"@type":"ListItem","position":2,"name":"INSS 2025: Guia completo de valores, tabela e pagamento da guia"}]},{"@type":"WebSite","@id":"https:\/\/www.em.com.br\/emfoco\/#website","url":"https:\/\/www.em.com.br\/emfoco\/","name":"Estado de Minas - Em foco","description":"Acompanhe as \u00faltimas not\u00edcias e fique bem informado sobre tudo o que acontece em Minas Gerais, Brasil e no mundo.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.em.com.br\/emfoco\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.em.com.br\/emfoco\/#\/schema\/person\/fb0a7f48c6fbb94b83f413a80f61917d","name":"Kelvin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.em.com.br\/emfoco\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e74f84337e6bf6c4c5e88fbdffa05270?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e74f84337e6bf6c4c5e88fbdffa05270?s=96&d=mm&r=g","caption":"Kelvin"},"sameAs":["https:\/\/www.em.com.br\/emfoco"],"url":"https:\/\/www.em.com.br\/emfoco\/author\/kelvinmyth\/"}]}},"_links":{"self":[{"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/posts\/19155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/comments?post=19155"}],"version-history":[{"count":3,"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/posts\/19155\/revisions"}],"predecessor-version":[{"id":19269,"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/posts\/19155\/revisions\/19269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/media\/18088"}],"wp:attachment":[{"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/media?parent=19155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/categories?post=19155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.em.com.br\/emfoco\/wp-json\/wp\/v2\/tags?post=19155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}