{"id":37462,"date":"2026-01-28T10:00:00","date_gmt":"2026-01-28T13:00:00","guid":{"rendered":"https:\/\/www.em.com.br\/apostas\/?p=37462"},"modified":"2026-01-27T16:42:59","modified_gmt":"2026-01-27T19:42:59","slug":"lazio-x-genoa-palpites-serie-a-tim-30-01","status":"publish","type":"post","link":"https:\/\/www.em.com.br\/apostas\/lazio-x-genoa-palpites-serie-a-tim-30-01\/","title":{"rendered":"Lazio x Genoa Palpites &#8211; Serie A TIM &#8211; 30\/01"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Lazio x Genoa Palpites<\/h2>\n\n\n\n\n\n<p>No Stadio Olimpico, <strong><strong><strong>Lazio x <\/strong><\/strong>Genoa<\/strong> v\u00e3o se encontrar na sexta-feira, dia 30, \u00e0s 16h45 (hor\u00e1rio de Bras\u00edlia), pela 23\u00aa rodada da <strong>Serie A TIM<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-wolverhampton-x-chelsea-palpites-dos-especialistas\">Lazio x Genoa: Palpite Campeonato Italiano &#8211; Palpites da Reda\u00e7\u00e3o<\/h2>\n\n\n\n<p>Veja os tr\u00eas progn\u00f3sticos indicados para esse jogo entre dois times de campanhas medianas. Al\u00e9m disso, voc\u00ea pode conferir <strong><a href=\"https:\/\/www.em.com.br\/apostas\/palpites\/\" target=\"_blank\" rel=\"noreferrer noopener\">os melhores palpites dos jogos de hoje<\/a><\/strong> produzido de forma gratuita pelo Estado de Minas.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>MELHORES PALPITES<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>ODDS<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>MELHORES CASAS<\/strong><\/td><\/tr><tr><td>Menos de 2,5 gols<\/td><td class=\"has-text-align-center\" data-align=\"center\">1.46 <\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/www.em.com.br\/apostas\/go-betboom-prono-br-pt\">Betboom<\/a><\/td><\/tr><tr><td>Menos de 10,5 escanteios<\/td><td class=\"has-text-align-center\" data-align=\"center\">1.39 <\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/www.em.com.br\/apostas\/go-superbet-prono\">Superbet<\/a><\/td><\/tr><tr><td>Boulaye Dia mais de 0,5 chutes no gol<\/td><td class=\"has-text-align-center\" data-align=\"center\">1.61 <\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/www.em.com.br\/apostas\/go-betdasorte-prono-br-pt\">Bet d\u00e1 Sorte<\/a><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n<article class=\"em-bookmaker em-bookmaker--light\">\n  \n  <div class=\"em-bookmaker__row\">\n\n    <div class=\"em-bookmaker__head\">\n              <div class=\"em-bookmaker__logo\" style=\"background:#303540\">\n          <picture><source type=\"image\/webp\" srcset=\"\/apostas\/wp-content\/cache\/em-core\/img\/c1\/c1d8973515c433da49b3fe48b21919607608bbc8.png.webp\"><img src=\"\/apostas\/wp-content\/cache\/em-core\/img\/c1\/c1d8973515c433da49b3fe48b21919607608bbc8.png\" alt=\"Novibet\" width=\"80\" height=\"80\" loading=\"lazy\" decoding=\"async\"><\/picture>        <\/div>\n            <div class=\"em-bookmaker__id\">\n        <span class=\"em-bookmaker__name\">Novibet<\/span>\n                  <div class=\"em-bookmaker__rating\" aria-label=\"4.5 de 5\">\n            <span class=\"em-bookmaker__rating-stars\" aria-hidden=\"true\">\u2605\u2605\u2605\u2605\u2605<\/span>\n          <\/div>\n              <\/div>\n    <\/div>\n\n          <div class=\"em-bookmaker__pros\">\n                  <div class=\"em-bookmaker__pros-item\">\n            <svg class=\"em-bookmaker__pros-check\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" aria-hidden=\"true\">\n              <circle cx=\"12\" cy=\"12\" r=\"10\" fill=\"#22c55e\"\/>\n              <path d=\"M7 12.5l3 3 7-7\" stroke=\"#fff\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" fill=\"none\"\/>\n            <\/svg>\n            <span class=\"em-bookmaker__pros-text\">Diversidade de apostas esportivas<\/span>\n          <\/div>\n                  <div class=\"em-bookmaker__pros-item\">\n            <svg class=\"em-bookmaker__pros-check\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" aria-hidden=\"true\">\n              <circle cx=\"12\" cy=\"12\" r=\"10\" fill=\"#22c55e\"\/>\n              <path d=\"M7 12.5l3 3 7-7\" stroke=\"#fff\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" fill=\"none\"\/>\n            <\/svg>\n            <span class=\"em-bookmaker__pros-text\">App para dispositivos Android<\/span>\n          <\/div>\n                  <div class=\"em-bookmaker__pros-item\">\n            <svg class=\"em-bookmaker__pros-check\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" aria-hidden=\"true\">\n              <circle cx=\"12\" cy=\"12\" r=\"10\" fill=\"#22c55e\"\/>\n              <path d=\"M7 12.5l3 3 7-7\" stroke=\"#fff\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" fill=\"none\"\/>\n            <\/svg>\n            <span class=\"em-bookmaker__pros-text\">Livestreaming de qualidade<\/span>\n          <\/div>\n              <\/div>\n    \n          <div class=\"em-bookmaker__bonus-box\">\n                  <p class=\"em-bookmaker__bonus-amount\">Odds Aumentadas!<\/p>\n                          <p class=\"em-bookmaker__bonus-name\">DESTAQUES<\/p>\n              <\/div>\n    \n    <div class=\"em-bookmaker__cta-stack\">\n                      <button type=\"button\"\n                class=\"em-bookmaker__code-box\"\n                data-copy=\"EMVIP\"\n                data-copy-default=\"Clique para copiar o c\u00f3digo\"\n                data-copy-done=\"Copiado!\"\n                                aria-label=\"Copiar c\u00f3digo EMVIP\">\n          <span class=\"em-bookmaker__code-label\" data-copy-target=\"label\">Clique para copiar o c\u00f3digo<\/span>\n          <span class=\"em-bookmaker__code-value\">\n                          <code>EMVIP<\/code>\n                        <svg class=\"em-bookmaker__code-icon\" width=\"14\" height=\"14\" viewBox=\"0 0 24 24\" fill=\"currentColor\" aria-hidden=\"true\">\n              <path d=\"M16 1H4c-1.1 0-2 .9-2 2v14h2V3h12V1zm3 4H8c-1.1 0-2 .9-2 2v14c0 1.1.9 2 2 2h11c1.1 0 2-.9 2-2V7c0-1.1-.9-2-2-2zm0 16H8V7h11v14z\"\/>\n            <\/svg>\n          <\/span>\n        <\/button>\n                    <a class=\"em-bookmaker__cta\"\n         href=\"https:\/\/www.em.com.br\/apostas\/go-novibet\"\n         rel=\"nofollow sponsored noopener\"\n         target=\"_blank\">\n        <span class=\"em-bookmaker__cta-text\">REGISTRAR-SE<\/span>\n        <span class=\"em-bookmaker__cta-arrow\" aria-hidden=\"true\">\u2192<\/span>\n      <\/a>\n    <\/div>\n\n  <\/div>\n\n      <p class=\"em-bookmaker__tc\">A participa\u00e7\u00e3o frequente em jogos exp\u00f5e os participantes ao risco\nde depend\u00eancia, dist\u00farbios patol\u00f3gicos do jogo e perda de valores de apostas. Leia em nosso site sobre as restri\u00e7\u00f5es ao apostador antes de apostar\n<\/p>\n  <\/article>\n\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-aposta-1-resultado-liverpool-empate-anula-pagando-1-72\">Menos de 2,5 gols, pagando 1.46 na Betboom<\/h3>\n\n\n\n<p>O maior problema da Lazio \u00e9 marcar tentos, pois vem tendo muitas dificuldades em chegar ao gol advers\u00e1rio, mas, por outro lado, sua defesa \u00e9 o ponto forte da equipe, estando entre as cinco melhores do Campeonato Italiano. Essas caracter\u00edsticas dos mandantes fizeram com que 15 dos \u00faltimos 17 jogos das \u00c1guias terminassem com menos de duas bolas na rede.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-aposta-3-mais-de-2-5-gols-pagando-1-70\">Menos de 10,5 escanteios, pagando 1.39 na Superbet<\/h3>\n\n\n\n<p>Com sua boa defesa e um time que consegue controlar bem a posse de bola, as partidas da Lazio v\u00eam sendo com poucos tiros de canto e, ainda por cima, ter\u00e1 um advers\u00e1rio que ataca pouco, contribuindo para nosso palpite. J\u00e1 s\u00e3o cinco jogos seguidos das \u00c1guias acabando com menos de dez escanteios.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-aposta-2-arsenal-marca-menos-de-1-5-gols-pagando-1-60\">Boulaye Dia mais de 0,5 chutes no gol, pagando 1.61 na Bet d\u00e1 Sorte<\/h3>\n\n\n\n<p>Com a sa\u00edda de Taty Castellano, o senegal\u00eas Boulaye Dia virou a refer\u00eancia do ataque \u2014 ele \u00e9 um atacante de for\u00e7a f\u00edsica, de \u00e1rea, que precisa de pouco espa\u00e7o para finalizar no gol, al\u00e9m de ser um bom cabeceador. Al\u00e9m disso, \u00e9 um atleta que vem buscando a confian\u00e7a do torcedor e essa \u00e9 uma \u00f3tima oportunidade para ele se provar.<\/p>\n\n\n<article class=\"em-bookmaker em-bookmaker--light\">\n  \n  <div class=\"em-bookmaker__row\">\n\n    <div class=\"em-bookmaker__head\">\n              <div class=\"em-bookmaker__logo\" style=\"background:#303540\">\n          <picture><source type=\"image\/webp\" srcset=\"\/apostas\/wp-content\/cache\/em-core\/img\/c1\/c1d8973515c433da49b3fe48b21919607608bbc8.png.webp\"><img src=\"\/apostas\/wp-content\/cache\/em-core\/img\/c1\/c1d8973515c433da49b3fe48b21919607608bbc8.png\" alt=\"Novibet\" width=\"80\" height=\"80\" loading=\"lazy\" decoding=\"async\"><\/picture>        <\/div>\n            <div class=\"em-bookmaker__id\">\n        <span class=\"em-bookmaker__name\">Novibet<\/span>\n                  <div class=\"em-bookmaker__rating\" aria-label=\"4.5 de 5\">\n            <span class=\"em-bookmaker__rating-stars\" aria-hidden=\"true\">\u2605\u2605\u2605\u2605\u2605<\/span>\n          <\/div>\n              <\/div>\n    <\/div>\n\n          <div class=\"em-bookmaker__pros\">\n                  <div class=\"em-bookmaker__pros-item\">\n            <svg class=\"em-bookmaker__pros-check\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" aria-hidden=\"true\">\n              <circle cx=\"12\" cy=\"12\" r=\"10\" fill=\"#22c55e\"\/>\n              <path d=\"M7 12.5l3 3 7-7\" stroke=\"#fff\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" fill=\"none\"\/>\n            <\/svg>\n            <span class=\"em-bookmaker__pros-text\">Diversidade de apostas esportivas<\/span>\n          <\/div>\n                  <div class=\"em-bookmaker__pros-item\">\n            <svg class=\"em-bookmaker__pros-check\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" aria-hidden=\"true\">\n              <circle cx=\"12\" cy=\"12\" r=\"10\" fill=\"#22c55e\"\/>\n              <path d=\"M7 12.5l3 3 7-7\" stroke=\"#fff\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" fill=\"none\"\/>\n            <\/svg>\n            <span class=\"em-bookmaker__pros-text\">App para dispositivos Android<\/span>\n          <\/div>\n                  <div class=\"em-bookmaker__pros-item\">\n            <svg class=\"em-bookmaker__pros-check\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" aria-hidden=\"true\">\n              <circle cx=\"12\" cy=\"12\" r=\"10\" fill=\"#22c55e\"\/>\n              <path d=\"M7 12.5l3 3 7-7\" stroke=\"#fff\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" fill=\"none\"\/>\n            <\/svg>\n            <span class=\"em-bookmaker__pros-text\">Livestreaming de qualidade<\/span>\n          <\/div>\n              <\/div>\n    \n          <div class=\"em-bookmaker__bonus-box\">\n                  <p class=\"em-bookmaker__bonus-amount\">Odds Aumentadas!<\/p>\n                          <p class=\"em-bookmaker__bonus-name\">DESTAQUES<\/p>\n              <\/div>\n    \n    <div class=\"em-bookmaker__cta-stack\">\n                      <button type=\"button\"\n                class=\"em-bookmaker__code-box\"\n                data-copy=\"EMVIP\"\n                data-copy-default=\"Clique para copiar o c\u00f3digo\"\n                data-copy-done=\"Copiado!\"\n                                aria-label=\"Copiar c\u00f3digo EMVIP\">\n          <span class=\"em-bookmaker__code-label\" data-copy-target=\"label\">Clique para copiar o c\u00f3digo<\/span>\n          <span class=\"em-bookmaker__code-value\">\n                          <code>EMVIP<\/code>\n                        <svg class=\"em-bookmaker__code-icon\" width=\"14\" height=\"14\" viewBox=\"0 0 24 24\" fill=\"currentColor\" aria-hidden=\"true\">\n              <path d=\"M16 1H4c-1.1 0-2 .9-2 2v14h2V3h12V1zm3 4H8c-1.1 0-2 .9-2 2v14c0 1.1.9 2 2 2h11c1.1 0 2-.9 2-2V7c0-1.1-.9-2-2-2zm0 16H8V7h11v14z\"\/>\n            <\/svg>\n          <\/span>\n        <\/button>\n                    <a class=\"em-bookmaker__cta\"\n         href=\"https:\/\/www.em.com.br\/apostas\/go-novibet\"\n         rel=\"nofollow sponsored noopener\"\n         target=\"_blank\">\n        <span class=\"em-bookmaker__cta-text\">REGISTRAR-SE<\/span>\n        <span class=\"em-bookmaker__cta-arrow\" aria-hidden=\"true\">\u2192<\/span>\n      <\/a>\n    <\/div>\n\n  <\/div>\n\n      <p class=\"em-bookmaker__tc\">A participa\u00e7\u00e3o frequente em jogos exp\u00f5e os participantes ao risco\nde depend\u00eancia, dist\u00farbios patol\u00f3gicos do jogo e perda de valores de apostas. Leia em nosso site sobre as restri\u00e7\u00f5es ao apostador antes de apostar\n<\/p>\n  <\/article>\n\n\n\n\n<h2 class=\"wp-block-heading\">Lazio x Genoa &#8211; Odds de vit\u00f3ria (1X2)<\/h2>\n\n\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/gamelebi.com\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"461\" src=\"https:\/\/www.em.com.br\/apostas\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-02-at-11.51.52-1024x461.jpeg\" alt=\"https:\/\/gamelebi.com\/\" class=\"wp-image-24088\" srcset=\"https:\/\/www.em.com.br\/apostas\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-02-at-11.51.52-1024x461.jpeg 1024w, https:\/\/www.em.com.br\/apostas\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-02-at-11.51.52-300x135.jpeg 300w, https:\/\/www.em.com.br\/apostas\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-02-at-11.51.52-768x346.jpeg 768w, https:\/\/www.em.com.br\/apostas\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-02-at-11.51.52.jpeg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-onde-assistir-liverpool-x-arsenal\">Onde assistir Lazio x Genoa<\/h2>\n\n\n\n<p>O evento ter\u00e1 transmiss\u00e3o no canal por assinatura <strong>ESPN<\/strong>, no servi\u00e7o de streaming<strong> Disney+<\/strong> e no portal <strong>XSports<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-wolverhampton-x-chelsea-retrospecto-e-informacoes-relevantes\">Lazio x Genoa: como chegam para o confronto?<\/h2>\n\n\n\n<p>Em 133 confrontos, os clubes mantiveram uma rivalidade com vantagem para <em>Le Aquile<\/em>, que registraram 54 vit\u00f3rias contra 46 do oponente, com mais 34 empates. Devido a isso, a equipe assinalou mais tentos, totalizando 202, em compara\u00e7\u00e3o com os 175 da <strong><strong>Genoa<\/strong><\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Lazio <\/h3>\n\n\n\n<p>Ganhando 29 pontos at\u00e9 agora e ocupando a 9\u00aa coloca\u00e7\u00e3o, a <strong>Lazio<\/strong> est\u00e1 positiva. Nos \u00faltimos duelos teve um 0 x 0 com o <strong>Lecce<\/strong>, antes foi derrotado pelo <strong>Como<\/strong> por 3 x 0 e venceu por 1 x 0 diante a <strong>Verona<\/strong>, depois que empatou com a <strong>Fiorentina<\/strong> por 2 x 2 e perdeu contra o <strong><strong><strong>Napoli<\/strong><\/strong><\/strong> por 1 x 0.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Genoa<\/h3>\n\n\n\n<p>O <strong>Genoa<\/strong> conquistou 23 pontos e est\u00e1 assegurando a 13\u00aa coloca\u00e7\u00e3o na tabela. No \u00faltimo confronto venceu em um 3 x 2 contra o <strong>Bologna<\/strong>, vindo de um empate contra o <strong>Parma<\/strong> por 0 x 0, antes triunfou por 3 x 0 contra a <strong>Cagliari<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Lazio x Genoa &#8211; Pontos de Aten\u00e7\u00e3o<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Quem vence a partida?<\/h3>\n\n\n\n<p>A <strong>Lazio<\/strong> \u00e9 levemente favorita para esse confronto, pois seu time vem sendo regular dentro do campeonato, dando trabalho para as equipes do topo, e est\u00e1 melhor posicionada na tabela que o <strong>Genoa<\/strong>, que est\u00e1 entre os cinco piores visitantes da competi\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Qual time tem mais vit\u00f3rias?<\/h3>\n\n\n\n<p>Com 133 confrontos registrados entre as duas equipes, a <strong><strong><strong>Lazio <\/strong><\/strong><\/strong>saiu na frente com 54 resultados positivos, em vista dos 46 da <em>Rossoblu<\/em>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-ficha-tecnica-da-disputa\">Ficha t\u00e9cnica da disputa<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Partida: Lazio x Genoa<\/li>\n\n\n\n<li>Competi\u00e7\u00e3o: Campeonato Italiano<\/li>\n\n\n\n<li>Data: 30\/01<\/li>\n\n\n\n<li>Hor\u00e1rio: 16h45<\/li>\n\n\n\n<li>Local: Stadio Olimpico, em Roma<\/li>\n\n\n\n<li>Onde assistir: ESPN, Disney+ e XSports<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Lazio x Genoa Palpites No Stadio Olimpico, Lazio x Genoa v\u00e3o se encontrar na sexta-feira, dia 30, \u00e0s 16h45 (hor\u00e1rio de Bras\u00edlia), pela 23\u00aa rodada da Serie A TIM. Lazio x Genoa: Palpite Campeonato Italiano &#8211; Palpites da Reda\u00e7\u00e3o Veja os tr\u00eas progn\u00f3sticos indicados para esse jogo entre dois times de campanhas medianas. Al\u00e9m disso, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"mm_nova_slots_40244","format":"standard","meta":{"footnotes":""},"categories":[36,55],"tags":[47,42,44,46,45,43],"class_list":["post-37462","post","type-post","status-publish","format-standard","hentry","category-palpites","category-campeonato-italiano","tag-apostas","tag-bet-365","tag-betano","tag-odds","tag-palpites","tag-prognosticos"],"_links":{"self":[{"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/posts\/37462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/comments?post=37462"}],"version-history":[{"count":1,"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/posts\/37462\/revisions"}],"predecessor-version":[{"id":37467,"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/posts\/37462\/revisions\/37467"}],"wp:attachment":[{"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/media?parent=37462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/categories?post=37462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/tags?post=37462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}