{"id":37285,"date":"2026-01-26T23:29:00","date_gmt":"2026-01-27T02:29:00","guid":{"rendered":"https:\/\/www.em.com.br\/apostas\/?p=37285"},"modified":"2026-02-02T16:27:34","modified_gmt":"2026-02-02T19:27:34","slug":"corinthians-x-bahia-palpites-brasileirao-serie-a-28-01","status":"publish","type":"post","link":"https:\/\/www.em.com.br\/apostas\/corinthians-x-bahia-palpites-brasileirao-serie-a-28-01\/","title":{"rendered":"Corinthians x Bahia Palpites &#8211; Brasileir\u00e3o S\u00e9rie A \u2013 28\/01"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Corinthians x Bahia Palpites<\/h2>\n\n\n\n\n\n<p>Na quarta-feira, dia 28, <strong>Corinthians x Bahia <\/strong>duelam na Neo Qu\u00edmica Arena, \u00e0s 20h (hor\u00e1rio de Bras\u00edlia), pela 1\u00aa rodada do&nbsp;<strong>Brasileir\u00e3o<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-wolverhampton-x-chelsea-palpites-dos-especialistas\">Corinthians x Bahia: Palpite Campeonato Brasileiro &#8211; Palpites da Reda\u00e7\u00e3o<\/h2>\n\n\n\n<p>Disponibilizamos os tr\u00eas melhores progn\u00f3sticos para o duelo entre gigantes. Al\u00e9m disso, voc\u00ea pode conferir <strong><a href=\"https:\/\/www.em.com.br\/apostas\/palpites\/\" target=\"_blank\" rel=\"noreferrer noopener\">os melhores palpites dos jogos de hoje<\/a><\/strong> produzido de forma gratuita pelo Estado de Minas.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>MELHORES PALPITES<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>ODDS<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>MELHORES CASAS<\/strong><\/td><\/tr><tr><td>Corinthians menos de 1,5 gols<\/td><td class=\"has-text-align-center\" data-align=\"center\">1.61 <\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/www.em.com.br\/apostas\/go-betnacional-prono\">Betnacional<\/a><\/td><\/tr><tr><td>Bahia marca o 1\u00ba gol<\/td><td class=\"has-text-align-center\" data-align=\"center\">2.29 <\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/www.em.com.br\/apostas\/go-betdasorte-prono-br-pt\">Bet d\u00e1 Sorte<\/a><\/td><\/tr><tr><td>Mais de 2,5 defesas pelo goleiro do Corinthians<\/td><td class=\"has-text-align-center\" data-align=\"center\">1.87 <\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/www.em.com.br\/apostas\/go-superbet-prono\">Superbet<\/a><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Descubra os&nbsp;<strong><a href=\"https:\/\/www.em.com.br\/apostas\/apostas-brasileirao-serie-a\/\" target=\"_blank\" rel=\"noreferrer noopener\">melhores sites de apostas para apostar no Brasileir\u00e3o 2026<\/a><\/strong><\/li>\n<\/ul>\n\n\n<article class=\"em-bookmaker em-bookmaker--light\">\n  \n  <div class=\"em-bookmaker__row\">\n\n    <div class=\"em-bookmaker__head\">\n              <div class=\"em-bookmaker__logo\" style=\"background:#303540\">\n          <picture><source type=\"image\/webp\" srcset=\"\/apostas\/wp-content\/cache\/em-core\/img\/c1\/c1d8973515c433da49b3fe48b21919607608bbc8.png.webp\"><img src=\"\/apostas\/wp-content\/cache\/em-core\/img\/c1\/c1d8973515c433da49b3fe48b21919607608bbc8.png\" alt=\"Novibet\" width=\"80\" height=\"80\" loading=\"lazy\" decoding=\"async\"><\/picture>        <\/div>\n            <div class=\"em-bookmaker__id\">\n        <span class=\"em-bookmaker__name\">Novibet<\/span>\n                  <div class=\"em-bookmaker__rating\" aria-label=\"4.5 de 5\">\n            <span class=\"em-bookmaker__rating-stars\" aria-hidden=\"true\">\u2605\u2605\u2605\u2605\u2605<\/span>\n          <\/div>\n              <\/div>\n    <\/div>\n\n          <div class=\"em-bookmaker__pros\">\n                  <div class=\"em-bookmaker__pros-item\">\n            <svg class=\"em-bookmaker__pros-check\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" aria-hidden=\"true\">\n              <circle cx=\"12\" cy=\"12\" r=\"10\" fill=\"#22c55e\"\/>\n              <path d=\"M7 12.5l3 3 7-7\" stroke=\"#fff\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" fill=\"none\"\/>\n            <\/svg>\n            <span class=\"em-bookmaker__pros-text\">Diversidade de apostas esportivas<\/span>\n          <\/div>\n                  <div class=\"em-bookmaker__pros-item\">\n            <svg class=\"em-bookmaker__pros-check\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" aria-hidden=\"true\">\n              <circle cx=\"12\" cy=\"12\" r=\"10\" fill=\"#22c55e\"\/>\n              <path d=\"M7 12.5l3 3 7-7\" stroke=\"#fff\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" fill=\"none\"\/>\n            <\/svg>\n            <span class=\"em-bookmaker__pros-text\">App para dispositivos Android<\/span>\n          <\/div>\n                  <div class=\"em-bookmaker__pros-item\">\n            <svg class=\"em-bookmaker__pros-check\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" aria-hidden=\"true\">\n              <circle cx=\"12\" cy=\"12\" r=\"10\" fill=\"#22c55e\"\/>\n              <path d=\"M7 12.5l3 3 7-7\" stroke=\"#fff\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" fill=\"none\"\/>\n            <\/svg>\n            <span class=\"em-bookmaker__pros-text\">Livestreaming de qualidade<\/span>\n          <\/div>\n              <\/div>\n    \n          <div class=\"em-bookmaker__bonus-box\">\n                  <p class=\"em-bookmaker__bonus-amount\">Odds Aumentadas!<\/p>\n                          <p class=\"em-bookmaker__bonus-name\">DESTAQUES<\/p>\n              <\/div>\n    \n    <div class=\"em-bookmaker__cta-stack\">\n                      <button type=\"button\"\n                class=\"em-bookmaker__code-box\"\n                data-copy=\"EMVIP\"\n                data-copy-default=\"Clique para copiar o c\u00f3digo\"\n                data-copy-done=\"Copiado!\"\n                                aria-label=\"Copiar c\u00f3digo EMVIP\">\n          <span class=\"em-bookmaker__code-label\" data-copy-target=\"label\">Clique para copiar o c\u00f3digo<\/span>\n          <span class=\"em-bookmaker__code-value\">\n                          <code>EMVIP<\/code>\n                        <svg class=\"em-bookmaker__code-icon\" width=\"14\" height=\"14\" viewBox=\"0 0 24 24\" fill=\"currentColor\" aria-hidden=\"true\">\n              <path d=\"M16 1H4c-1.1 0-2 .9-2 2v14h2V3h12V1zm3 4H8c-1.1 0-2 .9-2 2v14c0 1.1.9 2 2 2h11c1.1 0 2-.9 2-2V7c0-1.1-.9-2-2-2zm0 16H8V7h11v14z\"\/>\n            <\/svg>\n          <\/span>\n        <\/button>\n                    <a class=\"em-bookmaker__cta\"\n         href=\"https:\/\/www.em.com.br\/apostas\/go-novibet\"\n         rel=\"nofollow sponsored noopener\"\n         target=\"_blank\">\n        <span class=\"em-bookmaker__cta-text\">REGISTRAR-SE<\/span>\n        <span class=\"em-bookmaker__cta-arrow\" aria-hidden=\"true\">\u2192<\/span>\n      <\/a>\n    <\/div>\n\n  <\/div>\n\n      <p class=\"em-bookmaker__tc\">A participa\u00e7\u00e3o frequente em jogos exp\u00f5e os participantes ao risco\nde depend\u00eancia, dist\u00farbios patol\u00f3gicos do jogo e perda de valores de apostas. Leia em nosso site sobre as restri\u00e7\u00f5es ao apostador antes de apostar\n<\/p>\n  <\/article>\n\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-aposta-1-resultado-liverpool-empate-anula-pagando-1-72\">Corinthians menos de 1,5 gols, pagando 1.61 na Betnacional<\/h3>\n\n\n\n<p>Com muitas dificuldades em balan\u00e7ar as redes, o Corinthians apenas uma vez nesta temporada marcou mais de um gol e ainda por cima vai enfrentar uma equipe que controla muito bem o ritmo e a posse de bola, atrapalhando ainda mais a vida do Tim\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-aposta-3-mais-de-2-5-gols-pagando-1-70\">Bahia marca o 1\u00ba gol, pagando 2.29 na Bet d\u00e1 Sorte<\/h3>\n\n\n\n<p>O Bahia vem no mesmo ritmo da temporada passada, uma equipe muito boa ofensivamente, em todos os jogos do Campeonato Baiano o clube saiu na frente e vai ter agora um advers\u00e1rio que comete muitos erros defensivos, que podem ser aproveitados por eles.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-aposta-2-arsenal-marca-menos-de-1-5-gols-pagando-1-60\">Mais de 2,5 defesas pelo goleiro do Corinthians, pagando 1.87 na Superbet<\/h3>\n\n\n\n<p>Por o Bahia ser uma equipe agressiva, que tem em m\u00e9dia mais de sete chutes no gol, far\u00e1 Hugo Souza trabalhar, ele que \u00e9 um xod\u00f3 da torcida do Corinthians e goleiro de sele\u00e7\u00e3o brasileira, vem para garantir sua vaga na Copa.<\/p>\n\n\n<article class=\"em-bookmaker em-bookmaker--light\">\n  \n  <div class=\"em-bookmaker__row\">\n\n    <div class=\"em-bookmaker__head\">\n              <div class=\"em-bookmaker__logo\" style=\"background:#303540\">\n          <picture><source type=\"image\/webp\" srcset=\"\/apostas\/wp-content\/cache\/em-core\/img\/c1\/c1d8973515c433da49b3fe48b21919607608bbc8.png.webp\"><img src=\"\/apostas\/wp-content\/cache\/em-core\/img\/c1\/c1d8973515c433da49b3fe48b21919607608bbc8.png\" alt=\"Novibet\" width=\"80\" height=\"80\" loading=\"lazy\" decoding=\"async\"><\/picture>        <\/div>\n            <div class=\"em-bookmaker__id\">\n        <span class=\"em-bookmaker__name\">Novibet<\/span>\n                  <div class=\"em-bookmaker__rating\" aria-label=\"4.5 de 5\">\n            <span class=\"em-bookmaker__rating-stars\" aria-hidden=\"true\">\u2605\u2605\u2605\u2605\u2605<\/span>\n          <\/div>\n              <\/div>\n    <\/div>\n\n          <div class=\"em-bookmaker__pros\">\n                  <div class=\"em-bookmaker__pros-item\">\n            <svg class=\"em-bookmaker__pros-check\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" aria-hidden=\"true\">\n              <circle cx=\"12\" cy=\"12\" r=\"10\" fill=\"#22c55e\"\/>\n              <path d=\"M7 12.5l3 3 7-7\" stroke=\"#fff\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" fill=\"none\"\/>\n            <\/svg>\n            <span class=\"em-bookmaker__pros-text\">Diversidade de apostas esportivas<\/span>\n          <\/div>\n                  <div class=\"em-bookmaker__pros-item\">\n            <svg class=\"em-bookmaker__pros-check\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" aria-hidden=\"true\">\n              <circle cx=\"12\" cy=\"12\" r=\"10\" fill=\"#22c55e\"\/>\n              <path d=\"M7 12.5l3 3 7-7\" stroke=\"#fff\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" fill=\"none\"\/>\n            <\/svg>\n            <span class=\"em-bookmaker__pros-text\">App para dispositivos Android<\/span>\n          <\/div>\n                  <div class=\"em-bookmaker__pros-item\">\n            <svg class=\"em-bookmaker__pros-check\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" aria-hidden=\"true\">\n              <circle cx=\"12\" cy=\"12\" r=\"10\" fill=\"#22c55e\"\/>\n              <path d=\"M7 12.5l3 3 7-7\" stroke=\"#fff\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" fill=\"none\"\/>\n            <\/svg>\n            <span class=\"em-bookmaker__pros-text\">Livestreaming de qualidade<\/span>\n          <\/div>\n              <\/div>\n    \n          <div class=\"em-bookmaker__bonus-box\">\n                  <p class=\"em-bookmaker__bonus-amount\">Odds Aumentadas!<\/p>\n                          <p class=\"em-bookmaker__bonus-name\">DESTAQUES<\/p>\n              <\/div>\n    \n    <div class=\"em-bookmaker__cta-stack\">\n                      <button type=\"button\"\n                class=\"em-bookmaker__code-box\"\n                data-copy=\"EMVIP\"\n                data-copy-default=\"Clique para copiar o c\u00f3digo\"\n                data-copy-done=\"Copiado!\"\n                                aria-label=\"Copiar c\u00f3digo EMVIP\">\n          <span class=\"em-bookmaker__code-label\" data-copy-target=\"label\">Clique para copiar o c\u00f3digo<\/span>\n          <span class=\"em-bookmaker__code-value\">\n                          <code>EMVIP<\/code>\n                        <svg class=\"em-bookmaker__code-icon\" width=\"14\" height=\"14\" viewBox=\"0 0 24 24\" fill=\"currentColor\" aria-hidden=\"true\">\n              <path d=\"M16 1H4c-1.1 0-2 .9-2 2v14h2V3h12V1zm3 4H8c-1.1 0-2 .9-2 2v14c0 1.1.9 2 2 2h11c1.1 0 2-.9 2-2V7c0-1.1-.9-2-2-2zm0 16H8V7h11v14z\"\/>\n            <\/svg>\n          <\/span>\n        <\/button>\n                    <a class=\"em-bookmaker__cta\"\n         href=\"https:\/\/www.em.com.br\/apostas\/go-novibet\"\n         rel=\"nofollow sponsored noopener\"\n         target=\"_blank\">\n        <span class=\"em-bookmaker__cta-text\">REGISTRAR-SE<\/span>\n        <span class=\"em-bookmaker__cta-arrow\" aria-hidden=\"true\">\u2192<\/span>\n      <\/a>\n    <\/div>\n\n  <\/div>\n\n      <p class=\"em-bookmaker__tc\">A participa\u00e7\u00e3o frequente em jogos exp\u00f5e os participantes ao risco\nde depend\u00eancia, dist\u00farbios patol\u00f3gicos do jogo e perda de valores de apostas. Leia em nosso site sobre as restri\u00e7\u00f5es ao apostador antes de apostar\n<\/p>\n  <\/article>\n\n\n\n\n<h2 class=\"wp-block-heading\">Corinthians x Bahia &#8211; Odds de Vit\u00f3ria (1X2)<\/h2>\n\n\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/gamelebi.com\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/www.em.com.br\/apostas\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-02-at-11.51.52-1024x461.jpeg\" alt=\"\" class=\"wp-image-23865\"\/ loading=\"lazy\"><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-onde-assistir-liverpool-x-arsenal\">Onde assistir Corinthians x Bahia<\/h2>\n\n\n\n<p>O evento ter\u00e1 transmiss\u00e3o nos canais <strong>TV Globo <\/strong>e <strong>RecordTV<\/strong>, nos canais por assinatura <strong>SporTV <\/strong>e <strong>Premiere<\/strong>, no canal do YouTube <strong>Caz\u00e9TV <\/strong>e no servi\u00e7o de streaming <strong>Prime Video<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-wolverhampton-x-chelsea-retrospecto-e-informacoes-relevantes\">Corinthians x Bahia: como chegam para o confronto?<\/h2>\n\n\n\n<p>Tendo se enfrentado em v\u00e1rias partidas no Brasileir\u00e3o, os times acumulam 63 confrontos ao longo da hist\u00f3ria, com n\u00fameros melhores para o <strong><strong><strong><strong><strong><strong>Corinthians<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong>, que venceu 29 vezes contra 18 do <strong><strong><strong>Bahia<\/strong><\/strong><\/strong>, com mais 16 empates. Como resultado, o <em>Tim\u00e3o <\/em>marcou mais gols, sendo 88 comparado a 63 do advers\u00e1rio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Corinthians<\/h3>\n\n\n\n<p>Acumulando incr\u00edveis sete trof\u00e9us do Brasileir\u00e3o, o <strong>Corinthians <\/strong>\u00e9 o 3\u00ba que mais tem t\u00edtulos. Nos \u00faltimos jogos empatou contra o <strong><strong>S\u00e3o Paulo<\/strong><\/strong> por 1 x 1, antes sofreu uma baixa de 3 x 0 contra o <strong>Bragantino <\/strong>e derrotou a <strong>Ponte Preta<\/strong> em um 3 x 0 na estreia, depois que empatou com o <strong>Vasco<\/strong> por 0 x 0 no jogo de ida da Copa do Brasil.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Bahia<\/h3>\n\n\n\n<p>O <strong>Bahia<\/strong> \u00e9 dono de um t\u00edtulo apenas. Nos \u00faltimos compromissos a equipe ganhou do <strong><strong>Barcelona-BA<\/strong><\/strong> em um 5 x 1, tamb\u00e9m diante o <strong><strong>Gal\u00edcia<\/strong><\/strong> e o <strong><strong>Bahia de Feira<\/strong><\/strong>, ambos por 3 x 0.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Corinthians x Bahia &#8211; Pontos de Aten\u00e7\u00e3o<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Quem vence a partida?<\/h3>\n\n\n\n<p>Para esse jogo o <strong>Bahia <\/strong>\u00e9 favorito, levou a melhor em cima do <strong>Corinthians <\/strong>temporada passada fez um Campeonato Brasileiro de alto n\u00edvel ganhando de <strong>Palmeiras <\/strong>e <strong>Flamengo <\/strong>e chega para esse confronto com cinco vit\u00f3rias consecutivas, al\u00e9m do mais o <em>Tim\u00e3o <\/em>deve jogar com um time misto por conta da final da Supercopa do Brasil.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Qual time tem mais vit\u00f3rias?<\/h3>\n\n\n\n<p>Os times tiveram 63 oportunidades para entrar em campo, desse montante, o <strong><strong><strong><strong><strong><strong>Corinthians<\/strong> <\/strong><\/strong><\/strong><\/strong><\/strong>venceu 29 partidas, enquanto o <strong><strong>Bahia <\/strong><\/strong>triunfou em 18.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-ficha-tecnica-da-disputa\">Ficha t\u00e9cnica da disputa<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Partida: Corinthians x Bahia<\/li>\n\n\n\n<li>Competi\u00e7\u00e3o: Campeonato Brasileiro<\/li>\n\n\n\n<li>Data: 28\/01<\/li>\n\n\n\n<li>Hor\u00e1rio: 20h<\/li>\n\n\n\n<li>Local: Neo Qu\u00edmica Arena, em S\u00e3o Paulo<\/li>\n\n\n\n<li>Onde assistir: TV Globo, RecordTV, SporTV, Premiere, Caz\u00e9TV e Prime Video<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Corinthians x Bahia Palpites Na quarta-feira, dia 28, Corinthians x Bahia duelam na Neo Qu\u00edmica Arena, \u00e0s 20h (hor\u00e1rio de Bras\u00edlia), pela 1\u00aa rodada do&nbsp;Brasileir\u00e3o. Corinthians x Bahia: Palpite Campeonato Brasileiro &#8211; Palpites da Reda\u00e7\u00e3o Disponibilizamos os tr\u00eas melhores progn\u00f3sticos para o duelo entre gigantes. Al\u00e9m disso, voc\u00ea pode conferir os melhores palpites dos jogos [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"mm_nova_slots_40244","format":"standard","meta":{"footnotes":""},"categories":[36,37],"tags":[47,42,44,46,45,43],"class_list":["post-37285","post","type-post","status-publish","format-standard","hentry","category-palpites","category-brasileirao-seriea","tag-apostas","tag-bet-365","tag-betano","tag-odds","tag-palpites","tag-prognosticos"],"_links":{"self":[{"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/posts\/37285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/comments?post=37285"}],"version-history":[{"count":4,"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/posts\/37285\/revisions"}],"predecessor-version":[{"id":37759,"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/posts\/37285\/revisions\/37759"}],"wp:attachment":[{"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/media?parent=37285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/categories?post=37285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/tags?post=37285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}