{"id":37070,"date":"2026-01-23T22:34:00","date_gmt":"2026-01-24T01:34:00","guid":{"rendered":"https:\/\/www.em.com.br\/apostas\/?p=37070"},"modified":"2026-01-24T15:34:41","modified_gmt":"2026-01-24T18:34:41","slug":"santos-x-bragantino-palpites-paulistao-25-01","status":"publish","type":"post","link":"https:\/\/www.em.com.br\/apostas\/santos-x-bragantino-palpites-paulistao-25-01\/","title":{"rendered":"Santos x Bragantino Palpites &#8211; Paulist\u00e3o &#8211; 25\/01"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Santos x Bragantino Palpites<\/h2>\n\n\n\n\n\n<p>No domingo, dia 25, <strong>Santos x Bragantino<\/strong> duelam no Vila Belmiro, \u00e0s 16h (hor\u00e1rio de Bras\u00edlia), pela 5\u00aa rodada do&nbsp;<strong>Paulist\u00e3o<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-wolverhampton-x-chelsea-palpites-dos-especialistas\">Santos x Bragantino: Palpite Campeonato Paulista &#8211; Palpites da Reda\u00e7\u00e3o<\/h2>\n\n\n\n<p>Disponibilizamos os tr\u00eas melhores progn\u00f3sticos para o jogo do <em>Peixe<\/em>. Al\u00e9m disso, voc\u00ea pode conferir <strong><a href=\"https:\/\/www.em.com.br\/apostas\/palpites\/\" target=\"_blank\" rel=\"noreferrer noopener\">os melhores palpites dos jogos de hoje<\/a><\/strong> produzido de forma gratuita pelo Estado de Minas.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>MELHORES PALPITES<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>ODDS<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>MELHORES CASAS<\/strong><\/td><\/tr><tr><td>Mais de 1,5 gols <\/td><td class=\"has-text-align-center\" data-align=\"center\">1.36 <\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/www.em.com.br\/apostas\/go-betnacional-prono\">Betnacional<\/a><\/td><\/tr><tr><td>Menos de 5,5 cart\u00f5es <\/td><td class=\"has-text-align-center\" data-align=\"center\">1.68<\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/www.em.com.br\/apostas\/go-betdasorte-prono-br-pt\">Bet d\u00e1 Sorte<\/a><\/td><\/tr><tr><td>Mais de 25,5 finaliza\u00e7\u00f5es<\/td><td class=\"has-text-align-center\" data-align=\"center\">1.72 <\/td><td class=\"has-text-align-center\" data-align=\"center\"><a href=\"https:\/\/www.em.com.br\/apostas\/go-superbet-prono\">Superbet<\/a><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n<article class=\"em-bookmaker em-bookmaker--light\">\n  \n  <div class=\"em-bookmaker__row\">\n\n    <div class=\"em-bookmaker__head\">\n              <div class=\"em-bookmaker__logo\" style=\"background:#303540\">\n          <picture><source type=\"image\/webp\" srcset=\"\/apostas\/wp-content\/cache\/em-core\/img\/c1\/c1d8973515c433da49b3fe48b21919607608bbc8.png.webp\"><img src=\"\/apostas\/wp-content\/cache\/em-core\/img\/c1\/c1d8973515c433da49b3fe48b21919607608bbc8.png\" alt=\"Novibet\" width=\"80\" height=\"80\" loading=\"lazy\" decoding=\"async\"><\/picture>        <\/div>\n            <div class=\"em-bookmaker__id\">\n        <span class=\"em-bookmaker__name\">Novibet<\/span>\n                  <div class=\"em-bookmaker__rating\" aria-label=\"4.5 de 5\">\n            <span class=\"em-bookmaker__rating-stars\" aria-hidden=\"true\">\u2605\u2605\u2605\u2605\u2605<\/span>\n          <\/div>\n              <\/div>\n    <\/div>\n\n          <div class=\"em-bookmaker__pros\">\n                  <div class=\"em-bookmaker__pros-item\">\n            <svg class=\"em-bookmaker__pros-check\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" aria-hidden=\"true\">\n              <circle cx=\"12\" cy=\"12\" r=\"10\" fill=\"#22c55e\"\/>\n              <path d=\"M7 12.5l3 3 7-7\" stroke=\"#fff\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" fill=\"none\"\/>\n            <\/svg>\n            <span class=\"em-bookmaker__pros-text\">Diversidade de apostas esportivas<\/span>\n          <\/div>\n                  <div class=\"em-bookmaker__pros-item\">\n            <svg class=\"em-bookmaker__pros-check\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" aria-hidden=\"true\">\n              <circle cx=\"12\" cy=\"12\" r=\"10\" fill=\"#22c55e\"\/>\n              <path d=\"M7 12.5l3 3 7-7\" stroke=\"#fff\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" fill=\"none\"\/>\n            <\/svg>\n            <span class=\"em-bookmaker__pros-text\">App para dispositivos Android<\/span>\n          <\/div>\n                  <div class=\"em-bookmaker__pros-item\">\n            <svg class=\"em-bookmaker__pros-check\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" aria-hidden=\"true\">\n              <circle cx=\"12\" cy=\"12\" r=\"10\" fill=\"#22c55e\"\/>\n              <path d=\"M7 12.5l3 3 7-7\" stroke=\"#fff\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" fill=\"none\"\/>\n            <\/svg>\n            <span class=\"em-bookmaker__pros-text\">Livestreaming de qualidade<\/span>\n          <\/div>\n              <\/div>\n    \n          <div class=\"em-bookmaker__bonus-box\">\n                  <p class=\"em-bookmaker__bonus-amount\">Odds Aumentadas!<\/p>\n                          <p class=\"em-bookmaker__bonus-name\">DESTAQUES<\/p>\n              <\/div>\n    \n    <div class=\"em-bookmaker__cta-stack\">\n                      <button type=\"button\"\n                class=\"em-bookmaker__code-box\"\n                data-copy=\"EMVIP\"\n                data-copy-default=\"Clique para copiar o c\u00f3digo\"\n                data-copy-done=\"Copiado!\"\n                                aria-label=\"Copiar c\u00f3digo EMVIP\">\n          <span class=\"em-bookmaker__code-label\" data-copy-target=\"label\">Clique para copiar o c\u00f3digo<\/span>\n          <span class=\"em-bookmaker__code-value\">\n                          <code>EMVIP<\/code>\n                        <svg class=\"em-bookmaker__code-icon\" width=\"14\" height=\"14\" viewBox=\"0 0 24 24\" fill=\"currentColor\" aria-hidden=\"true\">\n              <path d=\"M16 1H4c-1.1 0-2 .9-2 2v14h2V3h12V1zm3 4H8c-1.1 0-2 .9-2 2v14c0 1.1.9 2 2 2h11c1.1 0 2-.9 2-2V7c0-1.1-.9-2-2-2zm0 16H8V7h11v14z\"\/>\n            <\/svg>\n          <\/span>\n        <\/button>\n                    <a class=\"em-bookmaker__cta\"\n         href=\"https:\/\/www.em.com.br\/apostas\/go-novibet\"\n         rel=\"nofollow sponsored noopener\"\n         target=\"_blank\">\n        <span class=\"em-bookmaker__cta-text\">REGISTRAR-SE<\/span>\n        <span class=\"em-bookmaker__cta-arrow\" aria-hidden=\"true\">\u2192<\/span>\n      <\/a>\n    <\/div>\n\n  <\/div>\n\n      <p class=\"em-bookmaker__tc\">A participa\u00e7\u00e3o frequente em jogos exp\u00f5e os participantes ao risco\nde depend\u00eancia, dist\u00farbios patol\u00f3gicos do jogo e perda de valores de apostas. Leia em nosso site sobre as restri\u00e7\u00f5es ao apostador antes de apostar\n<\/p>\n  <\/article>\n\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-aposta-1-resultado-liverpool-empate-anula-pagando-1-72\">Mais de 1,5 gols, pagando 1.36 na Betnacional<\/h3>\n\n\n\n<p>Esse \u00e9 mais um duelo para o Peixe, que sofreu gol em todas as rodadas do Campeonato Paulista, mas sua for\u00e7a jogando em casa \u00e9 impressionante, foi buscar o resultado aos 90 minutos no cl\u00e1ssico da \u00faltima rodada, na Vila Belmiro.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-aposta-3-mais-de-2-5-gols-pagando-1-70\">Menos de 5,5 cart\u00f5es, pagando 1.68 na Bet d\u00e1 Sorte<\/h3>\n\n\n\n<p>Depois do festival de cart\u00f5es da partida entre Santos x Corinthians, o time da casa precisa se segurar nas faltas para n\u00e3o receber amarelo e ter jogadores pendurados para a \u00faltima rodada, j\u00e1 o Bragantino n\u00e3o teve nenhuma partida na competi\u00e7\u00e3o com mais de quatro cart\u00f5es.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-aposta-2-arsenal-marca-menos-de-1-5-gols-pagando-1-60\">Mais de 25,5 finaliza\u00e7\u00f5es, pagando 1.72 na Superbet<\/h3>\n\n\n\n<p>O Santos \u00e9 uma equipe que arrisca muito, sua m\u00e9dia de finaliza\u00e7\u00f5es \u00e9 de 13,5, com um ataque pouco criativo a alternativa do Peixe \u00e9 o chute de longa dist\u00e2ncia, por\u00e9m do outro lado temos uma das melhores equipes do campeonato, sendo o segundo time que mais marcou gols.<\/p>\n\n\n<article class=\"em-bookmaker em-bookmaker--light\">\n  \n  <div class=\"em-bookmaker__row\">\n\n    <div class=\"em-bookmaker__head\">\n              <div class=\"em-bookmaker__logo\" style=\"background:#303540\">\n          <picture><source type=\"image\/webp\" srcset=\"\/apostas\/wp-content\/cache\/em-core\/img\/c1\/c1d8973515c433da49b3fe48b21919607608bbc8.png.webp\"><img src=\"\/apostas\/wp-content\/cache\/em-core\/img\/c1\/c1d8973515c433da49b3fe48b21919607608bbc8.png\" alt=\"Novibet\" width=\"80\" height=\"80\" loading=\"lazy\" decoding=\"async\"><\/picture>        <\/div>\n            <div class=\"em-bookmaker__id\">\n        <span class=\"em-bookmaker__name\">Novibet<\/span>\n                  <div class=\"em-bookmaker__rating\" aria-label=\"4.5 de 5\">\n            <span class=\"em-bookmaker__rating-stars\" aria-hidden=\"true\">\u2605\u2605\u2605\u2605\u2605<\/span>\n          <\/div>\n              <\/div>\n    <\/div>\n\n          <div class=\"em-bookmaker__pros\">\n                  <div class=\"em-bookmaker__pros-item\">\n            <svg class=\"em-bookmaker__pros-check\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" aria-hidden=\"true\">\n              <circle cx=\"12\" cy=\"12\" r=\"10\" fill=\"#22c55e\"\/>\n              <path d=\"M7 12.5l3 3 7-7\" stroke=\"#fff\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" fill=\"none\"\/>\n            <\/svg>\n            <span class=\"em-bookmaker__pros-text\">Diversidade de apostas esportivas<\/span>\n          <\/div>\n                  <div class=\"em-bookmaker__pros-item\">\n            <svg class=\"em-bookmaker__pros-check\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" aria-hidden=\"true\">\n              <circle cx=\"12\" cy=\"12\" r=\"10\" fill=\"#22c55e\"\/>\n              <path d=\"M7 12.5l3 3 7-7\" stroke=\"#fff\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" fill=\"none\"\/>\n            <\/svg>\n            <span class=\"em-bookmaker__pros-text\">App para dispositivos Android<\/span>\n          <\/div>\n                  <div class=\"em-bookmaker__pros-item\">\n            <svg class=\"em-bookmaker__pros-check\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" aria-hidden=\"true\">\n              <circle cx=\"12\" cy=\"12\" r=\"10\" fill=\"#22c55e\"\/>\n              <path d=\"M7 12.5l3 3 7-7\" stroke=\"#fff\" stroke-width=\"2.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" fill=\"none\"\/>\n            <\/svg>\n            <span class=\"em-bookmaker__pros-text\">Livestreaming de qualidade<\/span>\n          <\/div>\n              <\/div>\n    \n          <div class=\"em-bookmaker__bonus-box\">\n                  <p class=\"em-bookmaker__bonus-amount\">Odds Aumentadas!<\/p>\n                          <p class=\"em-bookmaker__bonus-name\">DESTAQUES<\/p>\n              <\/div>\n    \n    <div class=\"em-bookmaker__cta-stack\">\n                      <button type=\"button\"\n                class=\"em-bookmaker__code-box\"\n                data-copy=\"EMVIP\"\n                data-copy-default=\"Clique para copiar o c\u00f3digo\"\n                data-copy-done=\"Copiado!\"\n                                aria-label=\"Copiar c\u00f3digo EMVIP\">\n          <span class=\"em-bookmaker__code-label\" data-copy-target=\"label\">Clique para copiar o c\u00f3digo<\/span>\n          <span class=\"em-bookmaker__code-value\">\n                          <code>EMVIP<\/code>\n                        <svg class=\"em-bookmaker__code-icon\" width=\"14\" height=\"14\" viewBox=\"0 0 24 24\" fill=\"currentColor\" aria-hidden=\"true\">\n              <path d=\"M16 1H4c-1.1 0-2 .9-2 2v14h2V3h12V1zm3 4H8c-1.1 0-2 .9-2 2v14c0 1.1.9 2 2 2h11c1.1 0 2-.9 2-2V7c0-1.1-.9-2-2-2zm0 16H8V7h11v14z\"\/>\n            <\/svg>\n          <\/span>\n        <\/button>\n                    <a class=\"em-bookmaker__cta\"\n         href=\"https:\/\/www.em.com.br\/apostas\/go-novibet\"\n         rel=\"nofollow sponsored noopener\"\n         target=\"_blank\">\n        <span class=\"em-bookmaker__cta-text\">REGISTRAR-SE<\/span>\n        <span class=\"em-bookmaker__cta-arrow\" aria-hidden=\"true\">\u2192<\/span>\n      <\/a>\n    <\/div>\n\n  <\/div>\n\n      <p class=\"em-bookmaker__tc\">A participa\u00e7\u00e3o frequente em jogos exp\u00f5e os participantes ao risco\nde depend\u00eancia, dist\u00farbios patol\u00f3gicos do jogo e perda de valores de apostas. Leia em nosso site sobre as restri\u00e7\u00f5es ao apostador antes de apostar\n<\/p>\n  <\/article>\n\n\n\n\n<h2 class=\"wp-block-heading\">Santos x Bragantino &#8211; Odds de Vit\u00f3ria (1X2)<\/h2>\n\n\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/gamelebi.com\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"461\" src=\"https:\/\/www.em.com.br\/apostas\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-02-at-11.51.52-1-1024x461.jpeg\" alt=\"\" class=\"wp-image-24908\" srcset=\"https:\/\/www.em.com.br\/apostas\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-02-at-11.51.52-1-1024x461.jpeg 1024w, https:\/\/www.em.com.br\/apostas\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-02-at-11.51.52-1-300x135.jpeg 300w, https:\/\/www.em.com.br\/apostas\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-02-at-11.51.52-1-768x346.jpeg 768w, https:\/\/www.em.com.br\/apostas\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-02-at-11.51.52-1.jpeg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-onde-assistir-liverpool-x-arsenal\">Onde assistir Santos x Bragantino<\/h2>\n\n\n\n<p>O evento ter\u00e1 transmiss\u00e3o no canal aberto <strong>RecordTV<\/strong>, no canal de YouTube <strong>Caz\u00e9TV<\/strong>, nos servi\u00e7os de streaming <strong>TNT Sports <\/strong>e <strong>Max <\/strong>e nos portais <strong>Sportynet <\/strong>e <strong>Zapping Sports<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-wolverhampton-x-chelsea-retrospecto-e-informacoes-relevantes\">Santos x Bragantino: como chegam para o confronto?<\/h2>\n\n\n\n<p>Totalizando impressionantes 51 jogos entre as equipes, o <strong>Santos<\/strong> conquistou 22 vit\u00f3rias, seu advers\u00e1rio tem 12, acompanhados por 17 empates. Essa performance se traduz na quantidade de gols, com o<em> Santista Alvinegro <\/em>contabilizando 87 gols contra aos 57 do <strong><strong><strong>Bragantino<\/strong><\/strong><\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Santos<\/h3>\n\n\n\n<p>Somando cinco pontos, o <strong>Santos <\/strong>est\u00e1 em 8\u00ba lugar. O time vem ap\u00f3s ter dois 1 x 1, diante o <strong>Corinthians<\/strong> e o <strong>Guarani<\/strong>, antes foi derrotado pelo <strong>Palmeiras<\/strong> em um 1 x 0, depois de vencer o <strong>Novorizontino <\/strong>na estreia por 2 x 1, o <strong>Cruzeiro<\/strong>, o <strong>Juventude<\/strong> e o <strong>Sport<\/strong>, ambos por 3 x 0.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Bragantino<\/h3>\n\n\n\n<p>Fazendo uma campanha incr\u00edvel, o <strong>Bragantino <\/strong>juntou dez pontos e ocupa o 1\u00ba lugar. O time chega ap\u00f3s empatar com o <strong>Mirassol<\/strong> por 0 x 0, depois de ganhar em um 5 x 0 diante o <strong>Botafogo-SP<\/strong>, contra o <strong>Corinthians<\/strong> em um 3 x 0 e do <strong>Noroeste<\/strong> em um 1 x 0 na estreia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Santos x Bragantino &#8211; Pontos de Aten\u00e7\u00e3o<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Quem vence a partida?<\/h3>\n\n\n\n<p>O <strong>Santos<\/strong>, que vem apresentando dificuldades de balan\u00e7ar as redes, n\u00e3o perdeu nenhum jogo em casa, e do outro lado temos o <strong>Bragantino<\/strong>, que \u00e9 o l\u00edder da competi\u00e7\u00e3o e n\u00e3o foi derrotado em nenhuma rodada at\u00e9 o momento. Portanto, fica dif\u00edcil escolher um favorito.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Qual time tem mais vit\u00f3rias?<\/h3>\n\n\n\n<p>Com uma hist\u00f3ria de 51 jogos no confronto, o <strong>Santos<\/strong> se destaca como a equipe dominante, acumulando impressionantes 22 vit\u00f3rias. Por outro lado, o <strong><strong>Bragantino<\/strong><\/strong> venceu em 12.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-ficha-tecnica-da-disputa\">Ficha t\u00e9cnica da disputa<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Partida: Santos x Bragantino<\/li>\n\n\n\n<li>Competi\u00e7\u00e3o: Campeonato Paulista<\/li>\n\n\n\n<li>Data: 25\/01<\/li>\n\n\n\n<li>Hor\u00e1rio: 16h <\/li>\n\n\n\n<li>Local: Vila Belmiro, em Santos<\/li>\n\n\n\n<li>Onde assistir: RecordTV, Caz\u00e9TV, TNT Sports, Max, Sportynet e Zapping Sports<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Santos x Bragantino Palpites No domingo, dia 25, Santos x Bragantino duelam no Vila Belmiro, \u00e0s 16h (hor\u00e1rio de Bras\u00edlia), pela 5\u00aa rodada do&nbsp;Paulist\u00e3o. Santos x Bragantino: Palpite Campeonato Paulista &#8211; Palpites da Reda\u00e7\u00e3o Disponibilizamos os tr\u00eas melhores progn\u00f3sticos para o jogo do Peixe. Al\u00e9m disso, voc\u00ea pode conferir os melhores palpites dos jogos de [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"mm_nova_slots_40244","format":"standard","meta":{"footnotes":""},"categories":[36,86],"tags":[47,42,44,46,45,87,43],"class_list":["post-37070","post","type-post","status-publish","format-standard","hentry","category-palpites","category-campeonato-paulista","tag-apostas","tag-bet-365","tag-betano","tag-odds","tag-palpites","tag-paulistao","tag-prognosticos"],"_links":{"self":[{"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/posts\/37070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/comments?post=37070"}],"version-history":[{"count":3,"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/posts\/37070\/revisions"}],"predecessor-version":[{"id":37278,"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/posts\/37070\/revisions\/37278"}],"wp:attachment":[{"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/media?parent=37070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/categories?post=37070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.em.com.br\/apostas\/wp-json\/wp\/v2\/tags?post=37070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}